{"id":42480,"date":"2024-09-30T14:56:08","date_gmt":"2024-09-30T13:56:08","guid":{"rendered":"https:\/\/www.portalp.com\/protezione-dei-dati-personali\/"},"modified":"2025-05-21T10:04:39","modified_gmt":"2025-05-21T09:04:39","slug":"protezione-dei-dati-personali","status":"publish","type":"page","link":"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/","title":{"rendered":"Protezione dei dati personali"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;110px||||false|false&#8221; custom_margin_tablet=&#8221;110px||||false|false&#8221; custom_margin_phone=&#8221;70px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#005B94&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Protezione dei dati personali<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Responsabile del trattamento dei dati<\/h2>\n<p>Il responsabile del trattamento dei dati raccolti su questo sito \u00e8 <strong>Portalp France SAS<\/strong>, con sede 4, rue des Charpentiers, Zone Industrielle, 95330 DOMONT \u2013 France.<br \/>Per qualsiasi domanda relativa alla protezione dei Suoi dati personali, potete contattarci via email all\u2019indirizzo <a rel=\"noopener\">info@portalp.com<\/a> o per posta all\u2019indirizzo sopra indicato.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Dati personali raccolti<\/h2>\n<p>Durante l\u2019utilizzo del nostro sito, alcuni dati personali possono essere raccolti e trattati nei seguenti casi:<\/p>\n<ul>\n<li><strong>Navigazione sul sito<br \/><\/strong>Durante la visita vengono raccolti i seguenti dati di connessione e navigazione: \n<ul>\n<li>Indirizzo IP anonimizzato: il Suo indirizzo IP \u00e8 parzialmente anonimizzato per determinare la posizione in modo meno preciso.<\/li>\n<li>Dispositivo e browser utilizzati: questi dati vengono raccolti a fini statistici per migliorare la progettazione del sito e offrire un\u2019esperienza utente ottimale.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Moduli di contatto<br \/><\/strong>Compilando i nostri moduli, possiamo raccogliere i seguenti dati:\n<ul>\n<li>Nome,<\/li>\n<li>Cognome,<\/li>\n<li>Indirizzo email,<\/li>\n<li>Numero di telefono,<\/li>\n<li>Azienda e numero Siret,<\/li>\n<li>Messaggio.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Applicazione<\/strong><br \/>I moduli utilizzati per l\u2019invio delle candidature possono portarci a raccogliere anche: \n<ul>\n<li>Il Suo CV<\/li>\n<li>La Sua lettera di motivazione.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Finalit\u00e0 del trattamento<\/h2>\n<p>I dati raccolti vengono trattati per i seguenti scopi:<\/p>\n<ul>\n<li>Rispondere alle richieste e ai messaggi inviati tramite i moduli di contatto.<\/li>\n<li>Migliorare l\u2019esperienza utente sul sito tramite l\u2019analisi dei dati di navigazione.<\/li>\n<li>Gestire e valutare le candidature alle nostre offerte di lavoro.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Conservazione e condivisione dei dati<\/h2>\n<p>I dati raccolti tramite i moduli del sito web Portalp sono conservati sui nostri server situati in Francia.<\/p>\n<p>I dati di navigazione sono conservati sui server sicuri della societ\u00e0 Matomo (strumento di analisi web), situati in Germania.<\/p>\n<p>I dati raccolti sono utilizzati esclusivamente da <strong>Portalp <\/strong>e dai suoi distributori partner. Nessun dato viene condiviso con terze parti, salvo obblighi legali. <\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Durata di conservazione dei dati<\/h2>\n<p>I Suoi dati personali sono conservati solo per il tempo necessario al raggiungimento delle finalit\u00e0 per cui sono stati raccolti:<\/p>\n<ul>\n<li><strong>Dati di connessione<\/strong> : conservati per 13 mesi.<\/li>\n<li><strong>Moduli di contatto<\/strong>: conservati per 3 anni a partire dall\u2019ultimo contatto.<\/li>\n<li><strong>Candidature<\/strong>: conservate per 2 anni dopo l\u2019ultimo contatto se la candidatura non \u00e8 stata selezionata.<\/li>\n<\/ul>\n<p>Alla fine del periodo di conservazione, i dati vengono cancellati o anonimizzati, salvo diversi obblighi legali.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>I Suoi diritti<\/h2>\n<p>In conformit\u00e0 alla Legge francese &#8220;Informatique et Libert\u00e9s&#8221; del 6 gennaio 1978 modificata e al Regolamento Generale sulla Protezione dei Dati (GDPR), lei ha i seguenti diritti:<\/p>\n<ul>\n<li><strong>Diritto di accesso<\/strong>: potete ottenere una copia dei dati in nostro possesso che La riguardano.<\/li>\n<li><strong>Diritto di rettifica<\/strong>: potete richiedere la correzione di dati inesatti.<\/li>\n<li><strong>Diritto alla cancellazione<\/strong>: potete richiedere la cancellazione dei Suoi dati, in determinate circostanze.<\/li>\n<li><strong>Diritto alla limitazione<\/strong>: potete richiedere la limitazione del trattamento dei Suoi dati in determinati casi.<\/li>\n<li><strong>Diritto alla portabilit\u00e0<\/strong> : potete ricevere i dati che ci avete fornito in un formato strutturato.<\/li>\n<li><strong>Diritto di opposizione<\/strong>: potete opporvi in qualsiasi momento all\u2019utilizzo dei Suoi dati per fini commerciali.<\/li>\n<\/ul>\n<p>Per esercitare questi diritti, potete contattarci all\u2019indirizzo email <a rel=\"noopener\">info@portalp.com<\/a> o per posta: <strong>Portalp France SAS \u2013 4, rue des Charpentiers, 95330 DOMONT \u2013 France<\/strong>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Sicurezza dei dati<\/h2>\n<p>Adottiamo misure tecniche, fisiche e organizzative adeguate per proteggere i Suoi dati personali da accessi non autorizzati, modifiche, divulgazioni o distruzioni.<br \/>Queste misure includono, tra l\u2019altro: crittografia dei dati sensibili, firewall e accesso limitato alle informazioni.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Trasferimenti internazionali<\/h2>\n<p>I dati raccolti tramite i nostri moduli sono conservati sui server situati in Francia.<br \/>I dati di navigazione, invece, sono conservati sui server di Matomo situati in Germania. <\/p>\n<p>Nessun dato viene trasferito verso paesi terzi.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#005B94&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Cookies<\/h2>\n<h3>Che cos\u2019\u00e8 un cookie?<\/h3>\n<p>Un cookie \u00e8 un piccolo file di testo depositato sul Suo dispositivo (computer, tablet, smartphone) quando navigate su un sito web.<br \/>Serve a raccogliere informazioni sulla vostra navigazione, personalizzare l\u2019esperienza utente e proporre contenuti pertinenti.<\/p>\n<h3>Tipi di cookie utilizzati<\/h3>\n<p>Utilizziamo esclusivamente cookie strettamente necessari al corretto funzionamento e alla sicurezza del sito:<\/p>\n<ul>\n<li><em>wp-wpml_current_language<\/em> et <em>language-switcher-display<\/em> : cookie utilizzati per salvare la lingua corrente del sito.<\/li>\n<li><em>Recaptcha <\/em>: cookie che protegge il sito dagli spam.<\/li>\n<\/ul>\n<h3>Gestione dei cookie<\/h3>\n<p>Potete in qualsiasi momento disattivare o eliminare i cookie tramite le impostazioni del Suo browser. Tuttavia, alcune funzionalit\u00e0 del sito potrebbero essere compromesse.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Aggiornamenti della politica<\/h2>\n<p>Ci riserviamo il diritto di modificare in qualsiasi momento la presente politica di protezione dei dati personali. Le modifiche entreranno in vigore dal momento della pubblicazione su questa pagina. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Protezione dei dati personaliResponsabile del trattamento dei dati Il responsabile del trattamento dei dati raccolti su questo sito \u00e8 Portalp France SAS, con sede 4, rue des Charpentiers, Zone Industrielle, 95330 DOMONT \u2013 France.Per qualsiasi domanda relativa alla protezione dei Suoi dati personali, potete contattarci via email all\u2019indirizzo info@portalp.com o per posta all\u2019indirizzo sopra indicato.Dati [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-42480","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protezione dei dati personali | Portalp<\/title>\n<meta name=\"description\" content=\"Scoprite come Portalp protegge i vostri dati personali, rispettando la riservatezza e gli standard RGPD per garantire la vostra sicurezza e fiducia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protezione dei dati personali | Portalp\" \/>\n<meta property=\"og:description\" content=\"Scoprite come Portalp protegge i vostri dati personali, rispettando la riservatezza e gli standard RGPD per garantire la vostra sicurezza e fiducia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/\" \/>\n<meta property=\"og:site_name\" content=\"Portalp\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T09:04:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png\" \/>\n\t<meta property=\"og:image:width\" content=\"375\" \/>\n\t<meta property=\"og:image:height\" content=\"142\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/protezione-dei-dati-personali\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/protezione-dei-dati-personali\\\/\",\"name\":\"Protezione dei dati personali | Portalp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/#website\"},\"datePublished\":\"2024-09-30T13:56:08+00:00\",\"dateModified\":\"2025-05-21T09:04:39+00:00\",\"description\":\"Scoprite come Portalp protegge i vostri dati personali, rispettando la riservatezza e gli standard RGPD per garantire la vostra sicurezza e fiducia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/protezione-dei-dati-personali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.portalp.com\\\/it\\\/protezione-dei-dati-personali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/protezione-dei-dati-personali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protezione dei dati personali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/\",\"name\":\"Portalp\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/#organization\",\"name\":\"Portalp\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"width\":375,\"height\":142,\"caption\":\"Portalp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/portalp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protezione dei dati personali | Portalp","description":"Scoprite come Portalp protegge i vostri dati personali, rispettando la riservatezza e gli standard RGPD per garantire la vostra sicurezza e fiducia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/","og_locale":"it_IT","og_type":"article","og_title":"Protezione dei dati personali | Portalp","og_description":"Scoprite come Portalp protegge i vostri dati personali, rispettando la riservatezza e gli standard RGPD per garantire la vostra sicurezza e fiducia.","og_url":"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/","og_site_name":"Portalp","article_modified_time":"2025-05-21T09:04:39+00:00","og_image":[{"width":375,"height":142,"url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/","url":"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/","name":"Protezione dei dati personali | Portalp","isPartOf":{"@id":"https:\/\/www.portalp.com\/it\/#website"},"datePublished":"2024-09-30T13:56:08+00:00","dateModified":"2025-05-21T09:04:39+00:00","description":"Scoprite come Portalp protegge i vostri dati personali, rispettando la riservatezza e gli standard RGPD per garantire la vostra sicurezza e fiducia.","breadcrumb":{"@id":"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalp.com\/it\/protezione-dei-dati-personali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.portalp.com\/it\/"},{"@type":"ListItem","position":2,"name":"Protezione dei dati personali"}]},{"@type":"WebSite","@id":"https:\/\/www.portalp.com\/it\/#website","url":"https:\/\/www.portalp.com\/it\/","name":"Portalp","description":"","publisher":{"@id":"https:\/\/www.portalp.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalp.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.portalp.com\/it\/#organization","name":"Portalp","url":"https:\/\/www.portalp.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.portalp.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","width":375,"height":142,"caption":"Portalp"},"image":{"@id":"https:\/\/www.portalp.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/portalp"]}]}},"_links":{"self":[{"href":"https:\/\/www.portalp.com\/it\/wp-json\/wp\/v2\/pages\/42480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalp.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.portalp.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/it\/wp-json\/wp\/v2\/comments?post=42480"}],"version-history":[{"count":0,"href":"https:\/\/www.portalp.com\/it\/wp-json\/wp\/v2\/pages\/42480\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.portalp.com\/it\/wp-json\/wp\/v2\/media?parent=42480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}