{"id":22345,"date":"2024-07-03T07:19:31","date_gmt":"2024-07-03T06:19:31","guid":{"rendered":"https:\/\/www.portalp.com\/solutions\/portes-automatiques\/portes-automatiques-pietonnes\/porte-automatique-coupe-feu\/"},"modified":"2025-07-08T15:10:38","modified_gmt":"2025-07-08T14:10:38","slug":"coupe-feu","status":"publish","type":"page","link":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/","title":{"rendered":"Portes automatiques coupe-feu"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;2fb65f90-98a0-4e30-8a9f-70483021bb90&#8243; custom_margin=&#8221;80px||||false|false&#8221; custom_margin_tablet=&#8221;80px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;100px||30px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;9193d5fb-c085-4e28-9dfe-5ff42f9908a7&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;0.8em&#8221; hover_enabled=&#8221;0&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><a href=\"https:\/\/www.portalp.com\/fr_gl\/\">Accueil<\/a> \u00bb <a href=\"https:\/\/www.portalp.com\/fr_gl\/solutions\/\">Solutions<\/a> \u00bb <a href=\"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/\">Portes automatiques<\/a> \u00bb <a href=\"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/\">Pi\u00e9tonnes<\/a> \u00bb Coupe-feu<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; module_id=&#8221;product-page-details&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;9193d5fb-c085-4e28-9dfe-5ff42f9908a7&#8243; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;||||false|false&#8221; custom_margin_phone=&#8221;|0px||0px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;12254&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||16px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][et_pb_code module_id=&#8221;product-sectors&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;]<strong><!-- [et_pb_line_break_holder] -->  Principaux secteurs d&#8217;utilisation :<!-- [et_pb_line_break_holder] --><\/strong><!-- [et_pb_line_break_holder] --><\/p>\n<div><!-- [et_pb_line_break_holder] --><span><a href=\"https:\/\/www.portalp.com\/fr_gl\/marches\/hotellerie-restauration\/\">H\u00f4tellerie Restauration<\/a><\/span><!-- [et_pb_line_break_holder] --><span><a href=\"https:\/\/www.portalp.com\/fr_gl\/marches\/administrations-et-collectivites\/\">Administrations<\/a><\/span><!-- [et_pb_line_break_holder] --><span><a href=\"https:\/\/www.portalp.com\/fr_gl\/marches\/commerces\/\">Commerces GMS<\/a><\/span><!-- [et_pb_line_break_holder] --><\/p>\n<div><!-- [et_pb_line_break_holder] -->  <a href=\"https:\/\/www.portalp.com\/fr_gl\/services\/bim-modelisation\/\" style=\"color:#B49988;display:flex;justify-content:space-around\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/bim.png\"><span>BIM mod\u00e9lisation 3D<\/span><\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;de278f8c-1b66-4528-b528-255fc598d47f&#8221; header_font=&#8221;|700|||||||&#8221; header_text_color=&#8221;#005B94&#8243; custom_margin=&#8221;||12px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Portes automatiques coupe-feu<\/h1>\n<p>[\/et_pb_text][et_pb_text module_id=&#8221;product-page-intro&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;de278f8c-1b66-4528-b528-255fc598d47f&#8221; text_text_color=&#8221;#005B94&#8243; custom_margin=&#8221;||24px|||&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>L&#8217;alliance de la s\u00e9curit\u00e9 en cas d\u2019incendie et du confort quotidien<\/p>\n<p>[\/et_pb_text][et_pb_tabs active_tab_background_color=&#8221;RGBA(255,255,255,0)&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; tab_line_height=&#8221;1.1em&#8221; body_link_text_color=&#8221;#2BABE2&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; hover_enabled=&#8221;0&#8243; custom_css_free_form=&#8221;||@media(max-width:980px) {||  selector .et_pb_all_tabs {||  padding: 0 10%;||  }||}&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; border_width_all=&#8221;0px&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_tab title=&#8221;Description&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Description<\/h3>\n<p>D\u00e9couvrez la porte automatique coupe-feu, con\u00e7ue pour stopper la propagation du feu dans les ERP et autres b\u00e2timents en cas d\u2019incendie. <\/p>\n<p>La porte automatique coupe-feu assure une protection optimale des personnes tout en alliant modernit\u00e9 et connectivit\u00e9.<\/p>\n<h4>Les plus<\/h4>\n<ul>\n<li>Retarde la propagation du feu pendant 30 minutes <i>(au del\u00e0, nous contacter) <\/i><\/li>\n<li>Fermeture automatique par dispositif m\u00e9canique \u00e0 contrepoids ind\u00e9pendant de toute source d\u2019\u00e9nergie<\/li>\n<li>Porte DAS (Dispositif Actionn\u00e9 de S\u00e9curit\u00e9)<\/li>\n<li>Classement feu EI2-30 conform\u00e9ment \u00e0 la norme EN 13501-2:20216<\/li>\n<li>PV d\u2019essais feu r\u00e9alis\u00e9s par laboratoire agr\u00e9\u00e9<\/li>\n<\/ul>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Caract\u00e9ristiques&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Caract\u00e9ristiques<\/h3>\n<table style=\"width: 100%;\" border=\"0\">\n<tbody>\n<tr>\n<td>Largeur de passage :<\/td>\n<td>730 \u00e0 2 400 mm selon configuration<\/td>\n<\/tr>\n<tr>\n<td>Hauteur de passage max :<\/td>\n<td>2 500 mm<\/td>\n<\/tr>\n<tr>\n<td>Dimensions m\u00e9canisme<\/td>\n<td>200 x 193 mm<\/td>\n<\/tr>\n<tr>\n<td>Poids vantaux<\/td>\n<td>jusqu&#8217;\u00e0 2 x 200 kg selon gamme<\/td>\n<\/tr>\n<tr>\n<td>Pose<\/td>\n<td>En applique, selon configuration et options<\/td>\n<\/tr>\n<tr>\n<td>Structure<\/td>\n<td>Aluminium<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-style: italic; font-size: 0.8em;\">Produits sur mesure et de nombreuses options possibles, contactez-nous !<\/span><\/p>\n<p><span style=\"font-style: italic; font-size: 0.8em;\"><\/span><\/p>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Ventes et services&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; body_link_text_color=&#8221;#2BABE2&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Ventes<\/h3>\n<p>Nos \u00e9quipes \u00e9valuent vos besoins, vos contraintes et vous conseillent pour d\u00e9finir les solutions appropri\u00e9es \u00e0 chaque projet.<\/p>\n<p>Nos prix s\u2019entendent fourniture et pose.<\/p>\n<h3>Services<\/h3>\n<p>Nous vous accompagnons durant tout le cycle de vie de votre installation :\u00a0 mise en service, r\u00e9paration, r\u00e9novation et maintenance.[\/et_pb_tab][et_pb_tab title=&#8221;Normes&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_link_text_color=&#8221;#2BABE2&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Normes<\/h3>\n<p>Nous fabriquons nos produits selon les normes en vigueur au niveau national et international afin d&#8217;assurer la s\u00e9curit\u00e9, l&#8217;accessibilit\u00e9 et le maintien en bon \u00e9tat de marche de l&#8217;ensemble de nos solutions d&#8217;ouvertures automatis\u00e9es.<\/p>\n<table style=\"width: 100%;\" border=\"0\">\n<tbody>\n<tr>\n<td style=\"border-radius: 10px;\">Classement feu EI2-30 EN 13501-2:2016 des produits de construction et \u00e9l\u00e9ments de b\u00e2timent<\/td>\n<\/tr>\n<tr>\n<td style=\"border-radius: 10px;\">Certification NF d\u00e9livr\u00e9e par l\u2019AFNOR selon le r\u00e9f\u00e9rentiel NF277 &#8211; N\u00b044 Portes r\u00e9sistant au feu en m\u00e9tal, conformit\u00e9 \u00e0 l\u2019arr\u00eat\u00e9 du 14 Mars 2011 et normes NF-S61-937-1, NF-S61-937-3<\/td>\n<\/tr>\n<tr>\n<td style=\"border-radius: 10px;\">CE \u2013 EN 1634-1 \u2013 EN 61000-6-3\/2 &#8211; EN 60335-1\/-2-103 \u2013EN 16005 \u2013 EN13849-1 \u2013 EN 13501-2<\/td>\n<\/tr>\n<tr>\n<td style=\"border-radius: 10px;\">Origine France Garantie : gammes coulissantes<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"display: flex; justify-content: space-around; text-align: center; margin-top: 20px;\"><a href=\"https:\/\/www.portalp.com\/fr_gl\/entreprise\/certifications\/\">Retrouvez nos certifications<\/a><\/div>\n<p>[\/et_pb_tab][\/et_pb_tabs][et_pb_code module_id=&#8221;product-cta&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_module=&#8221;3051&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div><!-- [et_pb_line_break_holder] -->  <a href=\"https:\/\/www.portalp.com\/fr_gl\/contacts\/demander-un-devis\/\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/demander-un-devis.png\" width=\"90px\"><!-- [et_pb_line_break_holder] -->  <pee style=\"font-style:italic;color:#005b94\">Demander un devis<\/pee><\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<div><!-- [et_pb_line_break_holder] -->   <a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/telechargements\/\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/telechargement.png\" width=\"90px\"><!-- [et_pb_line_break_holder] -->  <pee style=\"font-style:italic;color:#005b94\">T\u00e9l\u00e9charger la documentation<\/pee><\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<div><!-- [et_pb_line_break_holder] -->    <a href=\"https:\/\/www.portalp.com\/fr_gl\/realisations\/\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/visualiser.png\" width=\"90px\"><!-- [et_pb_line_break_holder] -->  <pee style=\"font-style:italic;color:#005b94\">D\u00e9couvrir nos r\u00e9alisations<\/pee><\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<div><!-- [et_pb_line_break_holder] -->  <a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/guide-de-choix\/\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/guide-choix.png\" width=\"90px\"><!-- [et_pb_line_break_holder] -->  <pee style=\"font-style:italic;color:#005b94\">Comment choisir ma porte automatique ?<\/pee><\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;personnalisation-porte-auto&#8221; module_class=&#8221;personnalisation-porte&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#E4DAD3&#8243; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;||||false|false&#8221; custom_margin_phone=&#8221;|0px||0px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;20px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Personnalisez votre porte automatique<\/h2>\n<p>[\/et_pb_text][et_pb_tabs active_tab_background_color=&#8221;RGBA(255,255,255,0)&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;1.2em&#8221; tab_line_height=&#8221;1.1em&#8221; body_link_text_color=&#8221;#2BABE2&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_padding=&#8221;||||false|true&#8221; custom_padding_tablet=&#8221;||||false|true&#8221; custom_padding_phone=&#8221;|20px||20px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; custom_css_main_element=&#8221;width:100%;&#8221; custom_css_free_form=&#8221;selector .options-wrapper figure {||  width:15%;||  margin-bottom:20px;||  display:flex;||  flex-direction:column;||  align-items:center;||}||||@media(max-width:1279px) {||  selector .options-wrapper figure {||  \twidth:30%;||\t}||}||||@media(max-width:450px) {||  selector .options-wrapper figure {||  \twidth:45%;||\t}||}||||selector .options-wrapper figcaption {||  margin-top:5px;||  text-align:center;||  font-size:0.8em;||}||||selector img {||  border-radius:10px;||}&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_tab title=&#8221;Caract\u00e9ristiques coupe-feu&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_text_align=&#8221;left&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Caract\u00e9ristiques<\/h3>\n<div class=\"onglet-flex-container\">\n<div style=\"width: 50%; text-align: left;\">\n<p>Les vantaux sont compos\u00e9s d\u2019un ch\u00e2ssis en aluminium robuste de 78 mm et, en standard, d\u2019un vitrage Contraflam\u00ae 30. Ils sont con\u00e7us pour stopper la propagation des flammes pendant 30 minutes.<\/p>\n<p>Ils sont \u00e9quip\u00e9s de joints intumescents qui se dilatent sous l\u2019effet de la chaleur, calfeutrant la porte pour emp\u00eacher la fum\u00e9e de passer.<\/p>\n<p>Leur fermeture est assur\u00e9e par un dispositif m\u00e9canique de contrepoids ind\u00e9pendant de toute source \u00e9lectrique.<br \/>Ce syst\u00e8me \u00e0 \u00e9nergie gravitationnelle contr\u00f4l\u00e9e est surveill\u00e9 en permanence par notre op\u00e9rateur haute performance, garantissant s\u00e9curit\u00e9 et fiabilit\u00e9 de fonctionnement.<a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/guide-de-choix\/\"><\/a><\/p>\n<p><a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/guide-de-choix\/\">&gt; En savoir plus sur les diff\u00e9rentes configurations<\/a><\/p>\n<\/div>\n<div style=\"width: 50%;\">\n<div style=\"display: flex; margin-bottom: 30px;\">\n<div style=\"width: 100%;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/07\/portalp_porte_coupe_feu_schema.png\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Vantaux et design&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_text_align=&#8221;left&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Vantaux et design<\/h3>\n<p>Notre porte coupe-feu est \u00e9quip\u00e9e de vantaux robustes r\u00e9sistant aux flammes pour une dur\u00e9e de 30 minutes.<\/p>\n<p>Ils combinent un ch\u00e2ssis au design sp\u00e9cifique et dot\u00e9s de profils \u00e0 3 chambres int\u00e9grant des entretoises thermiques pour limiter la propagation de chaleur. Le vitrage Contraflam\u00ae 30 est rapidement assembl\u00e9 avec des parcloses.<br \/>Diff\u00e9rentes options de vitrage r\u00e9sistant au feu sont possibles en simple ou double jusqu\u2019\u00e0 50 mm d\u2019\u00e9paisseur.<\/p>\n<p>Un cadre d\u2019habillage install\u00e9 sur la cloison assure une meilleure \u00e9tanch\u00e9it\u00e9 de l\u2019ensemble aux flammes et aux fum\u00e9es.<\/p>\n<div style=\"display: flex; justify-content: space-between;\" class=\"display-block-mobile\">\n<div style=\"width: 23%;\">\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/vignette-vantaux-coupe-feu-1.png\" \/><\/p>\n<ul>\n<li>Montage du vitrage par parcloses int\u00e9rieur\/ext\u00e9rieur<\/li>\n<li>Vitrage haute performance r\u00e9sistant au feu<\/li>\n<li>Guides int\u00e9rieurs\/ext\u00e9rieurs int\u00e9gr\u00e9s au ch\u00e2ssis<\/li>\n<\/ul>\n<\/div>\n<div style=\"width: 23%;\">\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/vignette-vantaux-coupe-feu-2.png\" \/><\/p>\n<ul>\n<li>Profils 3 chambres avec entretoises thermiques<\/li>\n<li>Cadre d\u2019habillage cloison<\/li>\n<\/ul>\n<\/div>\n<div style=\"width: 23%;\">\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/vignette-vantaux-coupe-feu-3.png\" \/><\/p>\n<ul>\n<li>Chariots de roulement adapt\u00e9s aux vantaux lourds<\/li>\n<\/ul>\n<\/div>\n<div style=\"width: 23%;\">\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/vignette-vantaux-coupe-feu-4.png\" \/><\/p>\n<ul>\n<li>Patin de guidage des vantaux<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/guide-de-choix\/\">En savoir plus sur les diff\u00e9rents types de vitrage<\/a><\/p>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Renforcer la s\u00e9curit\u00e9&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_text_align=&#8221;left&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>S\u00e9curit\u00e9<\/h3>\n<div class=\"onglet-flex-container\">\n<div style=\"width: 60%; padding: 20px;\">\n<p>La porte coupe-feu est dot\u00e9e d\u2019une combinaison in\u00e9dite de technologies, dont celle des bus CAN qui facilitent la connexion et la communication avec tous les p\u00e9riph\u00e9riques la porte.<br \/>Celle-ci peut ais\u00e9ment \u00eatre connect\u00e9e \u00e0 une alarme incendie pour se fermer automatiquement en cas de signal d\u2019alerte.<\/p>\n<p>La porte DAS (Dispositif Actionn\u00e9 de S\u00e9curit\u00e9) r\u00e9pond aux exigences des normes NFS 61937-1 et -3. Un d\u00e9clencheur manuel install\u00e9 \u00e0 proximit\u00e9 de la porte permet aux usagers de d\u00e9clencher la fermeture imm\u00e9diate en cas d\u2019urgence.<a href=\"#\"><\/a><\/p>\n<p><a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/guide-de-choix\/\">En savoir plus sur les dispositifs de commandes<\/a><\/p>\n<\/div>\n<div style=\"width: 40%; padding: 20px; text-align: center;\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/portalp_schema_incendie_1.png\" \/><\/div>\n<\/div>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Configurations et options&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_link_text_color=&#8221;#2BABE2&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div class=\"onglet-flex-container\">\n<div style=\"width: 100%;\">\n<h3>Configurations et options<\/h3>\n<p>La porte automatique coupe-feu s\u2019adapte \u00e0 chaque environnement et \u00e0 vos exigences.<\/p>\n<p>8 configurations de pose sont possibles avec des options pour assurer la protection d\u2019une zone d\u00e9finie en gardant la luminosit\u00e9 naturelle que procurent les vitrages coupe-feu :<\/p>\n<ul>\n<li>Porte coulissante simple ou double, vitrages EI30 simple ou double<\/li>\n<li>Avec ou sans vantaux fixes, vitrages EI30 ou EI60<\/li>\n<li>Option d\u2019imposte vitr\u00e9e, hauteur porte jusqu\u2019\u00e0 4 m<\/li>\n<li>Option fa\u00e7ade vitr\u00e9e avec vantaux fixes et impostes vitr\u00e9es, hauteur porte jusqu\u2019\u00e0 4 m, largeur bloc-porte jusqu\u2019\u00e0 5 m<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/guide-de-choix\/\">En savoir plus sur les diff\u00e9rents types de vitrage<\/a><\/p>\n<p style=\"padding: 20px; border: 1px solid #B49988; border-radius: 10px;\">Les dimensions maximales peuvent varier selon la configuration d\u2019un site. Chaque porte est unique et fait l\u2019objet d\u2019un plan technique d\u00e9taill\u00e9 avec mention des exigences de pose selon le support. <a href=\"https:\/\/www.portalp.com\/fr_gl\/contacts\/\">N\u2019h\u00e9sitez pas \u00e0 demander conseil \u00e0 nos experts.<\/a><\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_module=&#8221;23599&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"onglet-cta\"><!-- [et_pb_line_break_holder] -->    <a href=\"https:\/\/www.portalp.com\/fr_gl\/contacts\/demander-un-devis\/\"><!-- [et_pb_line_break_holder] -->      <\/p>\n<div><!-- [et_pb_line_break_holder] -->        <img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/demander-un-devis.png\"><!-- [et_pb_line_break_holder] -->        <pee style=\"font-style: italic; color: #005b94;\">Demander un devis<\/pee><!-- [et_pb_line_break_holder] -->    \t<\/div>\n<p><!-- [et_pb_line_break_holder] -->  \t<\/a><!-- [et_pb_line_break_holder] -->    <a href=\"https:\/\/www.portalp.com\/fr_gl\/outils-et-supports\/telechargements\/\"><!-- [et_pb_line_break_holder] -->  \t\t<\/p>\n<div><!-- [et_pb_line_break_holder] -->        <img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/telechargement.png\"><!-- [et_pb_line_break_holder] -->        <pee style=\"font-style: italic; color: #005b94;\">T\u00e9l\u00e9charger la documentation<\/pee><!-- [et_pb_line_break_holder] -->    \t<\/div>\n<p><!-- [et_pb_line_break_holder] -->  \t<\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||29px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Vos march\u00e9s<\/h2>\n<p>[\/et_pb_text][dica_divi_carousel item_width_tablet=&#8221;300px&#8221; item_width_phone=&#8221;270px&#8221; item_width_last_edited=&#8221;on|phone&#8221; loop=&#8221;on&#8221; arrow_nav=&#8221;on&#8221; dot_nav=&#8221;on&#8221; equal_height=&#8221;on&#8221; lazy_loading=&#8221;on&#8221; load_before_transition=&#8221;on&#8221; advanced_effect=&#8221;1&#8243; overlay_color_field_bgcolor=&#8221;rgba(255,255,255,0.85)&#8221; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Carousel march\u00e9s&#8221; module_class=&#8221;carousel-type-1&#8243; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; body_font=&#8221;|600|||||||&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_module=&#8221;23246&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][dica_divi_carouselitem admin_label=&#8221;Sites propres &#8211; Sites sensibles&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/salles-prores.jpg&#8221; image_alt=&#8221;sites propres et sites sensibles&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwMzkifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Salles propres<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Sant\u00e9 &#8211; Hospitalier&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/sante-hospitalier-scaled.jpg&#8221; image_alt=&#8221;secteur hospitalier&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijk4NzAifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Sant\u00e9<br \/>Hospitalier<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Cabinets d&#8217;architectes &#8211; Entreprises g\u00e9n\u00e9rales&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/archi-entreprise-generale.jpg&#8221; image_alt=&#8221;cabinet d&#8217;entreprises &#8211; entreprises g\u00e9n\u00e9rales&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4NzUifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Architectes<br \/>Entreprises g\u00e9n\u00e9rales<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Industries&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/industries.jpg&#8221; image_alt=&#8221;industries&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjExNzU1In19@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Industries<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Secteur bancaire&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/bancaire.jpg&#8221; image_alt=&#8221;secteur bancaire&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEyMzM5In19@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Secteur bancaire<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Administration et collectivit\u00e9s&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/administration-tertiaire.jpg&#8221; image_alt=&#8221;administrations et collectivit\u00e9s&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; body_font=&#8221;|600|||||||&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4ODUifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Administrations<br \/>Collectivit\u00e9s<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Commerces&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/commerces.jpg&#8221; image_alt=&#8221;commerces&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; body_font=&#8221;|600|||||||&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4ODgifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Commerces<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Hotellerie &#8211; Restauration&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/hotellerie-restauration.jpg&#8221; image_alt=&#8221;h\u00f4tellerie restauration&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTEifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>H\u00f4tellerie<br \/>Restauration<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Transport ferroviaire&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/transport-ferroviaire.jpg&#8221; image_alt=&#8221;transport ferroviaire&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE2NDEifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Transport ferroviaire<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Syndics &#8211; Copropri\u00e9t\u00e9s&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/copropriete.jpg&#8221; image_alt=&#8221;syndics et copropri\u00e9t\u00e9s&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTUifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Syndics<br \/>Copropri\u00e9t\u00e9<\/p>\n<p>[\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accueil \u00bb Solutions \u00bb Portes automatiques \u00bb Pi\u00e9tonnes \u00bb Coupe-feuPortes automatiques coupe-feuL&#8217;alliance de la s\u00e9curit\u00e9 en cas d\u2019incendie et du confort quotidienDescription D\u00e9couvrez la porte automatique coupe-feu, con\u00e7ue pour stopper la propagation du feu dans les ERP et autres b\u00e2timents en cas d\u2019incendie. La porte automatique coupe-feu assure une protection optimale des personnes tout en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12254,"parent":20382,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-22345","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portes automatiques coupe-feu | Portalp<\/title>\n<meta name=\"description\" content=\"Assurez la s\u00e9curit\u00e9 de votre \u00e9tablissement avec notre porte automatique coupe-feu qui retarde la propagation du feu et prot\u00e8ge les personnes durant l\u2019\u00e9vacuation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portes automatiques coupe-feu | Portalp\" \/>\n<meta property=\"og:description\" content=\"Assurez la s\u00e9curit\u00e9 de votre \u00e9tablissement avec notre porte automatique coupe-feu qui retarde la propagation du feu et prot\u00e8ge les personnes durant l\u2019\u00e9vacuation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/\" \/>\n<meta property=\"og:site_name\" content=\"Portalp\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T14:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_coupe_feu-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/\",\"name\":\"Portes automatiques coupe-feu | Portalp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/portalp_porte_automatique_coupe_feu-1.jpg\",\"datePublished\":\"2024-07-03T06:19:31+00:00\",\"dateModified\":\"2025-07-08T14:10:38+00:00\",\"description\":\"Assurez la s\u00e9curit\u00e9 de votre \u00e9tablissement avec notre porte automatique coupe-feu qui retarde la propagation du feu et prot\u00e8ge les personnes durant l\u2019\u00e9vacuation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/#breadcrumb\"},\"inLanguage\":\"fr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/portalp_porte_automatique_coupe_feu-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/portalp_porte_automatique_coupe_feu-1.jpg\",\"width\":1440,\"height\":1440,\"caption\":\"Portalp porte automatique coulissante simple coupe feu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/coupe-feu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solutions\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Portes automatiques\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Portes automatiques pi\u00e9tonnes\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/solutions\\\/portes-automatiques\\\/pietonnes\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Portes automatiques coupe-feu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/#website\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/\",\"name\":\"Portalp\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/#organization\",\"name\":\"Portalp\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"width\":375,\"height\":142,\"caption\":\"Portalp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/fr_gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/portalp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portes automatiques coupe-feu | Portalp","description":"Assurez la s\u00e9curit\u00e9 de votre \u00e9tablissement avec notre porte automatique coupe-feu qui retarde la propagation du feu et prot\u00e8ge les personnes durant l\u2019\u00e9vacuation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/","og_locale":"fr_FR","og_type":"article","og_title":"Portes automatiques coupe-feu | Portalp","og_description":"Assurez la s\u00e9curit\u00e9 de votre \u00e9tablissement avec notre porte automatique coupe-feu qui retarde la propagation du feu et prot\u00e8ge les personnes durant l\u2019\u00e9vacuation.","og_url":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/","og_site_name":"Portalp","article_modified_time":"2025-07-08T14:10:38+00:00","og_image":[{"width":1440,"height":1440,"url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_coupe_feu-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/","url":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/","name":"Portes automatiques coupe-feu | Portalp","isPartOf":{"@id":"https:\/\/www.portalp.com\/fr_gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/#primaryimage"},"image":{"@id":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_coupe_feu-1.jpg","datePublished":"2024-07-03T06:19:31+00:00","dateModified":"2025-07-08T14:10:38+00:00","description":"Assurez la s\u00e9curit\u00e9 de votre \u00e9tablissement avec notre porte automatique coupe-feu qui retarde la propagation du feu et prot\u00e8ge les personnes durant l\u2019\u00e9vacuation.","breadcrumb":{"@id":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/#breadcrumb"},"inLanguage":"fr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/"]}]},{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/#primaryimage","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_coupe_feu-1.jpg","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_coupe_feu-1.jpg","width":1440,"height":1440,"caption":"Portalp porte automatique coulissante simple coupe feu"},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/coupe-feu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.portalp.com\/fr_gl\/"},{"@type":"ListItem","position":2,"name":"Solutions","item":"https:\/\/www.portalp.com\/fr_gl\/solutions\/"},{"@type":"ListItem","position":3,"name":"Portes automatiques","item":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/"},{"@type":"ListItem","position":4,"name":"Portes automatiques pi\u00e9tonnes","item":"https:\/\/www.portalp.com\/fr_gl\/solutions\/portes-automatiques\/pietonnes\/"},{"@type":"ListItem","position":5,"name":"Portes automatiques coupe-feu"}]},{"@type":"WebSite","@id":"https:\/\/www.portalp.com\/fr_gl\/#website","url":"https:\/\/www.portalp.com\/fr_gl\/","name":"Portalp","description":"","publisher":{"@id":"https:\/\/www.portalp.com\/fr_gl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalp.com\/fr_gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr"},{"@type":"Organization","@id":"https:\/\/www.portalp.com\/fr_gl\/#organization","name":"Portalp","url":"https:\/\/www.portalp.com\/fr_gl\/","logo":{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/www.portalp.com\/fr_gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","width":375,"height":142,"caption":"Portalp"},"image":{"@id":"https:\/\/www.portalp.com\/fr_gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/portalp"]}]}},"_links":{"self":[{"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/pages\/22345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/comments?post=22345"}],"version-history":[{"count":0,"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/pages\/22345\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/pages\/20382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/media\/12254"}],"wp:attachment":[{"href":"https:\/\/www.portalp.com\/fr_gl\/wp-json\/wp\/v2\/media?parent=22345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}