{"id":37955,"date":"2024-05-13T12:23:34","date_gmt":"2024-05-13T11:23:34","guid":{"rendered":"https:\/\/www.portalp.com\/guia-de-seleccion\/"},"modified":"2025-07-23T14:31:05","modified_gmt":"2025-07-23T13:31:05","slug":"guia-de-seleccion","status":"publish","type":"page","link":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/","title":{"rendered":"Gu\u00eda de selecci\u00f3n"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;150px||40px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;0.8em&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<span><span><a href=\"https:\/\/www.portalp.com\/es\/\">Inicio<\/a><\/span><\/span>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#005B94&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">\u00bfC\u00f3mo elegir su puerta autom\u00e1tica?<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;||30px||false|false&#8221; sticky_position=&#8221;top&#8221; sticky_offset_top=&#8221;120px&#8221; sticky_limit_bottom=&#8221;row&#8221; sticky_position_tablet=&#8221;none&#8221; sticky_position_phone=&#8221;none&#8221; sticky_position_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div><div id=\"image-map-pro-f1b1c7be-258d-4c4d-9802-af249a724383\"><\/div><\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code module_id=&#8221;mecanisme-entrainement&#8221; module_class=&#8221;composant-porte&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_margin_tablet=&#8221;||10px||false|false&#8221; custom_margin_phone=&#8221;||40px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;|20px||20px|true|true&#8221; custom_padding_tablet=&#8221;20px||20px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_width_bottom=&#8221;3px&#8221; border_color_bottom=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;&#8221; background_enable_color__hover=&#8221;off&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color_gradient_stops__hover=&#8221;#f2f2f2 0%|rgba(228,218,211,0) 100%&#8221; use_background_color_gradient__hover=&#8221;on&#8221; background_color_gradient_direction__hover=&#8221;90deg&#8221;]<\/p>\n<div class=\"component-wrapper\" data-status=\"closed\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<h3>Mecanismo de accionamiento<\/h3>\n<p><a class=\"close-hidden-component-content\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/moins-beige.png\" width=\"25px\"><\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><pee>El mecanismo de accionamiento consta de un operador y componentes mec\u00e1nicos que permiten el moviemiento de la puerta.<!-- [et_pb_line_break_holder] --><\/pee><!-- [et_pb_line_break_holder] --><a class=\"display-hidden-component-content\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/plus-beige.png\" width=\"30px\"><\/a><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"hidden-component-content\"><!-- [et_pb_line_break_holder] --><pee><strong>El operador consta de los siguientes componentes:<\/strong><\/pee><!-- [et_pb_line_break_holder] --><\/p>\n<ul><!-- [et_pb_line_break_holder] -->  <\/p>\n<li><span style=\"color:#B49988;font-weight:600\">Un motor <\/span>que proporciona la potencia necesaria para mover las hojas. En nuestras gamas se utilizan 3 tipos de motor: sin escobillas 90W, sin escobillas 120W, escobillas 70W.   <\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li><span style=\"color:#B49988;font-weight:600\">Una fuente de alimentaci\u00f3n <\/span>que proporciona la energ\u00eda que necesita el motor. Nuestras gamas est\u00e1n equipadas con fuentes de alimentaci\u00f3n est\u00e1ndar o conmutadas compatibles con todo tipo de redes,   <\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li><span style=\"color:#B49988;font-weight:600\">Una unidad l\u00f3gica<\/span> que gestiona de forma inteligente todos los movimientos de la puerta, detecta los obst\u00e1culos y se comunica con su entorno.<\/li>\n<p><!-- [et_pb_line_break_holder] -->\t<\/p>\n<li><span style=\"color:#B49988;font-weight:600\">M\u00f3dulos electr\u00f3nicos adicionales<\/span> para conectar perif\u00e9ricos de entrada o salida, gestionar el funcionamiento en esclusa, bater\u00eda de reserva, motor redundante, dispositivo EMI, radares combinados, conexi\u00f3n Bluetooth, CAN bus, etc.<\/li>\n<p> <!-- [et_pb_line_break_holder] --><\/ul>\n<p><!-- [et_pb_line_break_holder] --><pee><strong>La cadena cinem\u00e1tica que asegura la apertura y el cierre se compone de:<\/strong><\/pee><!-- [et_pb_line_break_holder] --><\/p>\n<ul><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Carros fijados a las hojas<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Carril gu\u00eda<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Correa, polea y sistema de tope<\/li>\n<p><!-- [et_pb_line_break_holder] -->\t<\/p>\n<li>Carril de suelo seg\u00fan la configuraci\u00f3n de la puerta<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/ul>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_code module_id=&#8221;caisson&#8221; module_class=&#8221;composant-porte&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_margin_tablet=&#8221;||10px||false|false&#8221; custom_margin_phone=&#8221;||40px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;|20px||20px|true|true&#8221; custom_padding_tablet=&#8221;20px||20px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_css_free_form=&#8221;selector h4 {||  color: #005B94;||}&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_width_bottom=&#8221;3px&#8221; border_color_bottom=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;&#8221; background_enable_color__hover=&#8221;off&#8221; background_color_gradient_stops__hover=&#8221;#f2f2f2 0%|rgba(228,218,211,0) 100%&#8221; use_background_color_gradient__hover=&#8221;on&#8221; background_color_gradient_direction__hover=&#8221;90deg&#8221; background__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<div class=\"component-wrapper\" data-status=\"closed\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<h3>Caj\u00f3n<\/h3>\n<p><a class=\"close-hidden-component-content\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/moins-beige.png\" width=\"25px\"><\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><pee>El caj\u00f3n es la caja que aloja el mecanismo de accionamiento de la puerta.  <\/pee><!-- [et_pb_line_break_holder] --><a class=\"display-hidden-component-content\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/plus-beige.png\" width=\"30px\"><\/a><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"hidden-component-content\"><!-- [et_pb_line_break_holder] --><pee><strong>La elecci\u00f3n del caj\u00f3n viene determinada por :<\/strong><\/pee> <!-- [et_pb_line_break_holder] --><\/p>\n<ul><!-- [et_pb_line_break_holder] -->  <\/p>\n<li><span style=\"color: #B49988;font-weight:600\">La configuraci\u00f3n: <\/span>corredera, redonda, telesc\u00f3pica, etc.<\/li>\n<p> <!-- [et_pb_line_break_holder] --><\/p>\n<li><span style=\"color: #B49988;font-weight:600\">Las limitaciones de infraestructura e instalaci\u00f3n:<\/span> espacio disponible, estructura de soporte, limitaciones de instalaci\u00f3n, entorno, etc.<\/li>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<li><span style=\"color: #B49988;font-weight:600\">El uso:<\/span> aplicaci\u00f3n est\u00e1ndar o espec\u00edfica, apertura de salida de emergencia, cortafuego o herm\u00e9tica, tr\u00e1fico diario medio, intensivo o muy intensivo, condiciones especiales de uso, etc.<\/li>\n<p><!-- [et_pb_line_break_holder] --><\/ul>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<h4>Cajones de la gama Portalp<\/h4>\n<p> <!-- [et_pb_line_break_holder] -->  <\/p>\n<ul><!-- [et_pb_line_break_holder] -->    <\/p>\n<li><strong>Cajones para puertas correderas, telesc\u00f3picas y antip\u00e1nico:<\/strong><!-- [et_pb_line_break_holder] -->\n<ul><!-- [et_pb_line_break_holder] -->  \t\t\t<\/li>\n<li>Gama RS &#8211; Altura 12 cm &#8211; vers\u00e1til, todos los usos<\/li>\n<p> <!-- [et_pb_line_break_holder] -->\t\t\t\t<\/p>\n<li>Gama RS &#8211; Altura 12 cm &#8211; vers\u00e1til, todos los usos<!-- [et_pb_line_break_holder] -->\t\t\t\t<\/li>\n<li>Gama TINA &#8211; Altura 10 cm &#8211; compacta, uso est\u00e1ndar<\/li>\n<p><!-- [et_pb_line_break_holder] -->\t\t\t\t<\/p>\n<li>Gama LEANA (fuera de Francia) &#8211; Altura 10 cm &#8211; aplicaci\u00f3n ligera, uso sencillo<\/li>\n<p><!-- [et_pb_line_break_holder] -->\t\t\t<\/ul>\n<p><!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] -->    <\/p>\n<li><strong>Cajones para aplicaciones espec\u00edficas :<\/strong><!-- [et_pb_line_break_holder] -->\n<ul><!-- [et_pb_line_break_holder] -->\t\t\t\t<\/p>\n<li>RS RC2: puerta antirrobo<\/li>\n<p> <!-- [et_pb_line_break_holder] -->\t\t\t\t<\/p>\n<li>DIVA ECOENERGY: puerta con rotura de puente t\u00e9rmico<\/li>\n<p><!-- [et_pb_line_break_holder] -->\t\t\t\t<\/p>\n<li>DIVA COUPE FEU: puerta cortafuego<\/li>\n<p> <!-- [et_pb_line_break_holder] -->  \t\t<\/ul>\n<p><!-- [et_pb_line_break_holder] -->    <\/li>\n<p><!-- [et_pb_line_break_holder] -->    <\/p>\n<li><strong>Los cajones para aplicaciones hospitalarias &#8211; salas blancas:<\/strong><!-- [et_pb_line_break_holder] -->\n<ul><!-- [et_pb_line_break_holder] -->\t\t\t\t<\/p>\n<li>DIVA L Clean: puerta de fuga controlad<\/li>\n<p><!-- [et_pb_line_break_holder] -->      <\/p>\n<li>HDS Clean: herm\u00e9tica y anti-X<\/li>\n<p><!-- [et_pb_line_break_holder] -->  \t\t<\/ul>\n<p><!-- [et_pb_line_break_holder] -->    <\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/ul>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_code module_id=&#8221;vantaux&#8221; module_class=&#8221;composant-porte&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;131px&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;|20px||20px|true|true&#8221; custom_padding_tablet=&#8221;20px||20px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_width_bottom=&#8221;3px&#8221; border_color_bottom=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;&#8221; background_enable_color__hover=&#8221;off&#8221; background_color_gradient_stops__hover=&#8221;#f2f2f2 0%|rgba(228,218,211,0) 100%&#8221; use_background_color_gradient__hover=&#8221;on&#8221; background_color_gradient_direction__hover=&#8221;90deg&#8221; background__hover_enabled=&#8221;on|hover&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div class=\"component-wrapper\" data-status=\"closed\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<h3>Hojas<\/h3>\n<p><a class=\"close-hidden-component-content\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/moins-beige.png\" width=\"25px\"><\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><pee>Las hojas de una puerta autom\u00e1tica son las partes m\u00f3viles de la puerta que se abren y cierran autom\u00e1ticamente.<\/pee><!-- [et_pb_line_break_holder] --><a class=\"display-hidden-component-content\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/plus-beige.png\" width=\"30px\"><\/a><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"hidden-component-content\"><!-- [et_pb_line_break_holder] --><pee><strong>Las hojas se componen de :<\/strong><\/pee><!-- [et_pb_line_break_holder] --><\/p>\n<ul><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Marco de aluminio: es la estructura que enmarca y soporta la puerta. Forma el marco de la puerta.   <!\u2013- [et_pb_br_holder] -\u2013><span style=\"font-style:italic\">Para otros materiales, <a href=\"https:\/\/www.portalp.com\/es\/contactos\/\">cons\u00faltenos.<\/a><\/span><\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Relleno acristalado, semiacristalado o macizo  <\/li>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<li>Juntas alrededor del marco<\/li>\n<p><!-- [et_pb_line_break_holder] --><\/ul>\n<p><!-- [et_pb_line_break_holder] --><pee><strong>El tipo de relleno viene determinado por:<\/strong><\/pee><!-- [et_pb_line_break_holder] --><\/p>\n<ul><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>El aspecto deseado<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>La cantidad de luz natural necesaria  <\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>El aislamiento t\u00e9rmico requerido<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Los requisitos de seguridad<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Confidencialidad<\/li>\n<p><!-- [et_pb_line_break_holder] --><\/ul>\n<p><!-- [et_pb_line_break_holder] --><pee><strong>Rellenos comunes:<\/strong><\/pee><!-- [et_pb_line_break_holder] --><\/p>\n<ul><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Acristalamiento laminado<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Acristalamientos aislantes<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Acristalamiento antirrobo<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Vidrio templado<\/li>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<li>Acristalamiento ign\u00edfugo<!\u2013- [et_pb_br_holder] -\u2013><!-- [et_pb_line_break_holder] -->\n<li>Acristalamiento laminado<!\u2013- [et_pb_br_holder] -\u2013><span style=\"font-style:italic\">Para otras opciones, p\u00f3ngase en <a href=\"https:\/\/www.portalp.com\/es\/contactos\/\">contacto con nosotros<\/a>.<\/span><!\u2013- [et_pb_br_holder] -\u2013><!\u2013- [et_pb_br_holder] -\u2013><\/li>\n<p><!-- [et_pb_line_break_holder] --><\/ul>\n<p><!-- [et_pb_line_break_holder] --><a href=\"https:\/\/www.portalp.com\/download\/516\/portalp-rs\/42883\/gama-hojas-folleto-comercial.pdf?preview=1\">> Buscar documentaci\u00f3n<\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;comprendre-onglets&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_tabs _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_link_text_color=&#8221;#2BABE2&#8243; hover_enabled=&#8221;0&#8243; custom_css_free_form=&#8221;selector h3, selector h4 {||  color: #005b94;||}&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_tab title=&#8221;Hojas y relleno&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_css_free_form=&#8221;@media(max-width:1200px) {||  selector table {||  \tdisplay:block;||    overflow-x:scroll;||    font-size:0.8em;||  }||  selector table td:first-of-type, selector table th:first-of-type {||    min-width:200px !important;||  }||  selector table caption {||    text-align:left;||  }||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table style=\"text-align:center\" id=\"guide-vantaux\">\n<caption>Grosor del relleno<\/caption>\n<thead>\n<tr>\n<th>Gama de hojas<\/th>\n<th>Todos los tipos de 8 a 10,8 mm<\/th>\n<th>Todos los tipos de 13 a 15 mm<\/th>\n<th>Todos los tipos de 24 a 26 mm<\/th>\n<th>Todos los tipos 30 mm<\/th>\n<th>Doble acristalamiento de 34 a 36 mm<\/th>\n<th>Contraflam EI30 20 mm claro<\/th>\n<th>Contraflam EI30 20 mm \u00f3palo<\/th>\n<th>Pyrostop EI60 27 mm<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align:left\">G25<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:left\">G38<\/td>\n<td>\u2713<\/td>\n<td>\u2713<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:left\">G50 RPT (Rotura de Puente T\u00e9rmico)<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:left\">LUMINA todo cristal o G10<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:left\">HDS (Puerta herm\u00e9tica)  <\/p>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:left\">DL Clean (\u00cdndice de fugas)  <\/p>\n<td>\u2713<\/td>\n<td><\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:left\">Cortafuegos<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td>\u2713<\/td>\n<td>\u2713<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id=\"vantaux-design-wrap\" style=\"margin-top:50px\">\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/lumina-tout-verre-avec-fond.png\"><\/p>\n<p class=\"nom-vantail\">LUMINA todo vidrio<\/p>\n<hr>\n<p>Utilizaci\u00f3n<\/p>\n<ul>\n<li>Ligera, elegante, amplio claro de luz sin interrupci\u00f3n, recomendada para uso interior<\/li>\n<\/ul><\/div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/lumina-profils-fins-avec-fond.png\"><\/p>\n<p class=\"nom-vantail\">LUMINA G10<\/p>\n<hr>\n<p>Utilizaci\u00f3n<\/p>\n<ul>\n<li>Ligera y elegante, recomendada para uso interior<\/li>\n<\/ul><\/div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/gamme-25-avec-fond.png\"><\/p>\n<p class=\"nom-vantail\">G25<\/p>\n<hr>\n<p>Utilizaci\u00f3n<\/p>\n<ul>\n<li>Uso vers\u00e1til, perfiles delgados<\/li>\n<\/ul><\/div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/gamme-38-avec-fond.png\"><\/p>\n<p class=\"nom-vantail\">G38<\/p>\n<hr>\n<p>Utilizaci\u00f3n<\/p>\n<ul>\n<li>Accesos principales en todos los sectores<\/li>\n<li>Accesos seguros con cerradura de cilindro o cerradura motorizada<\/li>\n<li>Apertura antip\u00e1nico pivotante<\/li>\n<\/ul><\/div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/gamme-50-avec-fond.png\"><\/p>\n<p class=\"nom-vantail\">G50 RPT<\/p>\n<hr>\n<p>Utilizaci\u00f3n<\/p>\n<ul>\n<li>Aislamiento t\u00e9rmico de alto rendimiento, edificios ecorresponsables<\/li>\n<\/ul><\/div>\n<\/div>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Opciones y controles&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; custom_css_free_form=&#8221;selector strong {||  font-weight:600;||}||||selector h4 {||  color: #706F6F;||  margin-bottom:5px;||}||||selector ul li span {||  color: #b49988;||  font-weight:600;||}&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div class=\"onglet-toggle closed-tab\">\n<h3>Hojas<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<h4><strong>Travesa\u00f1o intermedio <\/strong><\/h4>\n<h4><strong>Z\u00f3calo escamoteable: <\/strong>aislamiento reforzado para la puerta con rotura de puente t\u00e9rmico, que proporciona un mejor aislamiento a nivel del suelo cuando las hojas est\u00e1n cerradas.<\/h4>\n<h4><strong>Decoraci\u00f3n de acristalamiento: <\/strong>identidad de marca, parte opaca&#8230;<\/h4>\n<p><span style=\"font-style: italic;\">Para otras opciones, <a href=\"https:\/\/www.portalp.com\/es\/contactos\/\">cons\u00faltenos.<\/a><\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"onglet-toggle closed-tab\">\n<h3>Dise\u00f1o<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<h4><strong>Acabado anodizado plata RAL o anodizado de color: <\/strong>elecci\u00f3n del color de la puerta<\/h4>\n<ul>\n<li>RAL: carta internacional de colores utilizada por todos los fabricantes para definir las diferentes tonalidades.\n<ul>\n<li>188 colores Portalp<\/li>\n<li>2 colores de aluminio<\/li>\n<li>Acabado mate o satinado disponible<\/li>\n<li>Posibilidad de bicolor (opcional bajo pedido)<\/li>\n<\/ul>\n<\/li>\n<li>Colores HPL (puertas de hospital):\n<ul>\n<li>M\u00e1s de 50 colores HPL<\/li>\n<li>6 colores est\u00e1ndar<\/li>\n<li>Otros colores opcionales bajo pedido<\/li>\n<\/ul>\n<\/li>\n<li>AS (anodizado plata): proceso de anodizado plateado de un metal. Referencia est\u00e1ndar utilizada por Portalp para el acabado \u00abplata satinado\u00bb de sus productos.<\/li>\n<li>Anodizado en color (opcional bajo pedido)<\/li>\n<\/ul>\n<h4><strong>Lacado especial de acero inoxidable (a petici\u00f3n): <\/strong>acabados especiales<\/h4>\n<h4><strong>Decoraci\u00f3n acristalada:<\/strong> opacidad para confidencialidad&#8230;.<\/h4>\n<p><span style=\"font-style: italic;\">Para otras opciones, <a href=\"https:\/\/www.portalp.com\/es\/contactos\/\">cons\u00faltenos.<\/a><\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"onglet-toggle closed-tab\">\n<h3>Seguridad<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<h4><strong>Aperturas de emergencia, espec\u00edficas y otras:<\/strong><\/h4>\n<ul>\n<li>Bater\u00eda de emergencia<\/li>\n<li>Salida de emergencia motorizada: fuera de Francia, segundo motor para abrir en caso de emergencia<\/li>\n<li>Dispositivo antip\u00e1nico (EMI-CO48 &#8211; Energ\u00eda mec\u00e1nica intr\u00ednseca): el sistema EMI se activa en caso de corte de corriente o de situaci\u00f3n de emergencia que requiera la apertura inmediata de las hojas.<br \/>Necesidad de apertura inmediata de las hojas. Se instala por defecto en la puerta en Francia (normas CO48).<\/li>\n<li>Dispositivos de seguridad de apertura\/cierre (NO NF Cortinas IR): detecci\u00f3n de obst\u00e1culos, objetos y fuerza (personas) cerca de las hojas. Radares unidireccionales\/bidireccionales instalados en los laterales del caj\u00f3n. Instalados en la puerta por defecto en Europa (norma EN 16005), opcionales para el resto del mundo.<\/li>\n<li>Barrera de infrarrojos: fuera de Europa, seguridad en el paso. Permite bloquear el cierre por detecci\u00f3n de obst\u00e1culos.<br \/>No disponible en Europa, ya que no cumple las normas europeas (para Europa, consulte S\u00e9curit\u00e9s Ouv\/ferm (NO NF Rideaux IR)).<\/li>\n<li>Carril de suelo: carril de suelo empotrado que debe preverse antes de la instalaci\u00f3n. Permite fijar y guiar la hoja. Soluci\u00f3n antibloqueo y antirrobo.\n<ul>\n<li>Discreto, baja altura<\/li>\n<li>Paso suave y sin sacudidas (cumple la norma PMR &lt; &lt; 20 mm)<\/li>\n<li>Instalaci\u00f3n: empotrada, atornillada, sellada o pegada<\/li>\n<li>Compatibilidad: hojas G25, G38, RPT<\/li>\n<li>Obligatorio para determinadas configuraciones de puertas telesc\u00f3picas<\/li>\n<\/ul>\n<\/li>\n<li>Tarjeta SAS universal: permite configurar 2 \u00f3 3 puertas en modo SAS. La configuraci\u00f3n en modo SAS ofrece una protecci\u00f3n \u00f3ptima de las zonas sensibles gestionando el flujo de personas y el calor.\n<ul>\n<li>Uso t\u00edpico: sector bancario, aeropuertos, salas blancas y lugares sensibles, etc.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h4><strong>Bloqueo\/desbloqueo:<\/strong><\/h4>\n<ul>\n<li>Cierre de gancho: mecanismo de cierre que utiliza ganchos o pernos para asegurar las hojas de la puerta en posici\u00f3n cerrada. Estos ganchos encajan en una placa de cierre o punto de fijaci\u00f3n correspondiente en el marco de la puerta, lo que garantiza un bloqueo estable y seguro. Refuerza el cierre de la puerta.<\/li>\n<li>Cerradura de falleba: con su mecanismo multipunto, una cerradura de falleba puede bloquear la puerta en varios puntos simult\u00e1neamente. Los puntos de cierre pueden situarse encima, en medio y debajo de la puerta.<\/li>\n<li>Cierre el\u00e9ctrico: cierre electromec\u00e1nico &#8211; cierre motorizado que impide la apertura de las hojas<\/li>\n<li>Desbloqueo manual de emergencia interior: con varilla de tracci\u00f3n<\/li>\n<li>Desbloqueo manual exterior (en hoja fija o jamba): caja para abrir con llave<\/li>\n<li>Bloqueo de seguridad positivo :<br \/>Desbloqueo de puertas en caso de emergencia &#8211; inverso al bloqueo est\u00e1ndar<\/li>\n<li>Cerradura motorizada antirrobo RC2<\/li>\n<li>Bloqueo del cap\u00f3 mediante llave o tornillo<\/li>\n<\/ul>\n<p><span style=\"font-style: italic;\">Para otras opciones, <a href=\"https:\/\/www.portalp.com\/es\/contactos\/\">cons\u00faltenos.<\/a><\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"onglet-toggle closed-tab\">\n<h3>Opciones y controles<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<h4><strong>Control de la puerta:<\/strong><\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>NAVIBLU: consola de control y parametrizaci\u00f3n &#8211; controla el automatismo a trav\u00e9s de una gran pantalla LCD. Acceso a todas las funciones y programaciones de la puerta. Visualizaci\u00f3n de modos e incidencias mediante pictogramas y n\u00fameros. Pulsador de rearme integrado, contador de ciclos y memoria de aver\u00edas&#8230;\n<ul>\n<li>Conexi\u00f3n CAN<\/li>\n<li>Selecci\u00f3n del modo de funcionamiento: autom\u00e1tico, entrada, salida, abierto, cerrado, manual<\/li>\n<li>Selecci\u00f3n del tipo de apertura: apertura amplia, apertura peque\u00f1a, apertura segura<\/li>\n<li>Ajustes de la puerta: modo de bloqueo, velocidades, fuerzas, frenado de la hoja, retardos de apertura\/cierre, anchura de apertura peque\u00f1a, zumbador activo o no, funci\u00f3n PMR, gesti\u00f3n de los comandos auxiliares, modo bater\u00eda, etc.<\/li>\n<li>Aprendizaje de comandos IR: hasta 20 teclas IR o mandos a distancia S<\/li>\n<li>Teclado bloqueado por c\u00f3digo modificable<\/li>\n<li>Reset<\/li>\n<li>Notificaci\u00f3n y an\u00e1lisis de cualquier incidencia<\/li>\n<li>Notificaci\u00f3n y an\u00e1lisis de cualquier incidencia<\/li>\n<li>Compatibilidad: RS<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h4><strong>Comandos involuntarios:<\/strong><\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Radar interior (NO NC Autocontrolado)<\/li>\n<li>Dispositivos de seguridad de apertura\/cierre (NO NC Cortinas IR): detecci\u00f3n de obst\u00e1culos, objetos y fuerza (personas) cerca de las hojas. Radares unidireccionales\/bidireccionales instalados en los laterales de la carcasa. Instalados en la puerta por defecto en Europa (norma EN 16005), opcionales para el resto del mundo.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h4><strong>Mandos voluntarios:<\/strong><\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>S &#8211; Mando a distancia NAVIBLU: mando a distancia de NAVIBLU<\/li>\n<li>Selector de llave de 6 posiciones (con Reset): selector de modo accionado por llave &#8211; abierto, cerrado, autom\u00e1tico, manual, reset&#8230; varios tama\u00f1os y configuraciones Montaje en pared o empotrado.<\/li>\n<li>Interruptor de membrana sin contacto MAGIC SWITCH: detector de apertura sin contacto, simple barrido de la mano. Medidas de higiene, confort y seguridad. Se\u00f1al de detecci\u00f3n luminosa. 80\u00d780 mm\n<ul>\n<li>Opci\u00f3n CHROMA ADVANCED: superficie y juntas antimicrobianas, animaciones LED, ajuste de sonido, se\u00f1al de entrada, etc.<\/li>\n<\/ul>\n<\/li>\n<li>Pulsador: interacci\u00f3n manual para abrir o cerrar la puerta.<\/li>\n<li>Interruptor con llave: uso de una llave para activar o desactivar el mecanismo de la puerta. Al requerir el uso de una llave, la puerta puede bloquearse o desbloquearse selectivamente, lo que permite restringir el acceso a determinadas personas o en momentos espec\u00edficos.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h4><strong>Otros sistemas de control de acceso:<\/strong><\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>M\u00f3dulo de entradas (NA\/NF\/Frecuencia): se utiliza para conectar otros sistemas a la puerta (por ejemplo, control de acceso).<\/li>\n<li>M\u00f3dulo de salida (2 rel\u00e9s): permite enviar una se\u00f1al para comunicar con otro sistema (por ejemplo, climatizaci\u00f3n, detecci\u00f3n de intrusos, etc.).<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span style=\"font-style: italic;\">Para otras opciones, <a href=\"https:\/\/www.portalp.com\/es\/contactos\/\">cons\u00faltenos.<\/a><\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"onglet-toggle closed-tab\">\n<h3>Applicaciones<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<ul>\n<li>Autodoor Pilot: controle su puerta autom\u00e1tica a distancia con su smartphone.\n<ul>\n<li>Se conecta a todos sus equipos<\/li>\n<li>Hasta 32 usuarios<\/li>\n<li>Estado de la puerta, selector de seis modos, orden de apertura autom\u00e1tica, orden de bloqueo\/desbloqueo, orden de apertura prioritaria, reset, hist\u00f3rico de incidencias, ancho de apertura, etc.<\/li>\n<li>Servicios: servicio posventa, localizaci\u00f3n de sucursales Portalp, etc.<\/li>\n<\/ul>\n<\/li>\n<li>Autodoor Master: dedicado a los profesionales autorizados (instaladores y mantenedores) para todas las configuraciones, ajustes y puestas en marcha. Permite poner en servicio las puertas autom\u00e1ticas r\u00e1pidamente desde un smartphone.\n<ul>\n<li>Gu\u00eda paso a paso de todas las etapas de configuraci\u00f3n<\/li>\n<li>Ayuda para la resoluci\u00f3n de problemas y el mantenimiento, informes e historiales de incidencias<\/li>\n<li>Asistencia para el diagn\u00f3stico<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Configuraciones&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; custom_css_free_form=&#8221;selector h4, selector h5 {||  color: #005B94;||  font-weight:600;||}||||selector img {||  border-radius:10px||}||||selector hr {||  border:none;||  height:1px;||  background-color:#b49988;||  margin:60px 0;||}&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4 style=\"font-size: 18px; margin-bottom: 20px;\">\u00bfQu\u00e9 diferencia hay entre una puerta telesc\u00f3pica, corredera, de 2 o 3 hojas?<\/h4>\n<h5>Puerta corredera autom\u00e1tica simple o doble<\/h5>\n<div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_configuration_coulissante_simple.jpg\" \/><img decoding=\"async\" style=\"margin: 15px 0 5px;\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/coulissante-simple.png\" \/><\/p>\n<p style=\"text-align: center;\">Corredera simple<br \/>Cierre a derecha o izquierda<\/p>\n<\/div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_configuration_coulissante_double_1.jpg\" \/><img decoding=\"async\" style=\"margin: 15px 0 5px;\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/coulissante-double.png\" \/><\/p>\n<p style=\"text-align: center;\">Doble corredera<br \/>Cierre centralizado<\/p>\n<\/div>\n<div>La puerta corredera es la configuraci\u00f3n m\u00e1s com\u00fan. A diferencia de la puerta corredera telesc\u00f3pica, consta de uno o dos paneles centrales de cristal que se abren cuando se detecta la presencia de una persona.<br \/>Una puerta corredera autom\u00e1tica puede ser simple (1 hoja corredera) o doble (2 hojas correderas). Las puertas dobles ofrecen una apertura m\u00e1s amplia.<a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/peatonales\/correderas-y-telescopicas\/\">Consulte nuestras puertas correderas autom\u00e1ticas de una hoja.<\/a>Puertas correderas para usos espec\u00edficos :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/peatonales\/rotura-de-puente-termico\/\">Puerta corredera con rotura de puente t\u00e9rmico<\/a><\/li>\n<li><a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/peatonales\/cortafuego\/\">Puerta corredera cortafuegos<\/a><\/li>\n<li><a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/peatonales\/antipanico\/\">Puerta corredera antip\u00e1nico<\/a><\/li>\n<li><a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/hospitales-y-salas-limpias\/puertas-hermeticas\/\">Puerta corredera herm\u00e9tica &#8211; anti-X<\/a><\/li>\n<li><a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/hospitales-y-salas-limpias\/control-de-aire-limitado\/\">Puerta corredera con control de aire limitado<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<hr \/>\n<h5>Puerta telesc\u00f3pica autom\u00e1tica simple o doble<\/h5>\n<div>\n<div><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_configuration_telescopique_simple_2_vantaux-1.jpg\" \/><br \/><img decoding=\"async\" style=\"margin: 15px 0 5px;\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/telesco-2-vantaux-simple.png\" \/><\/p>\n<p style=\"text-align: center;\">Hoja simple telesc\u00f3pica de 2 hojas<br \/>Cierre a derecha o izquierda<\/p>\n<p><img decoding=\"async\" style=\"margin: 15px 0 5px;\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/telesco-3-vantaux-simple.png\" \/><\/p>\n<p style=\"text-align: center;\">Hoja simple telesc\u00f3pica de 3 hojas<br \/>Cierre a derecha o izquierda<\/p>\n<\/div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_telescopique_double_4_vantaux.jpg\" \/><img decoding=\"async\" style=\"margin: 15px 0 5px;\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/telesco-2-vantaux-double.png\" \/><\/p>\n<p style=\"text-align: center;\">Telesc\u00f3pica de 4 hojas<br \/>Cierre centralizado<\/p>\n<p><img decoding=\"async\" style=\"margin: 15px 0 5px;\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/telesco-3-vantaux-double.png\" \/><\/p>\n<p style=\"text-align: center;\">Telesc\u00f3pica de 6 hojas<br \/>Cierre centralizado<\/p>\n<\/div>\n<div>Una puerta telesc\u00f3pica autom\u00e1tica se utiliza generalmente en entornos donde el espacio es limitado y se desea una apertura m\u00e1xima.<br \/>A diferencia de las puertas correderas, las telesc\u00f3picas est\u00e1n formadas por paneles que se pliegan y solapan al abrirse, maximizando la apertura disponible.<br \/>La elecci\u00f3n entre una puerta corredera y una telesc\u00f3pica depende de :<\/p>\n<ul>\n<li>El espacio disponible<\/li>\n<li>La anchura de apertura deseada<\/li>\n<li>La frecuencia de uso<\/li>\n<li>La est\u00e9tica y el dise\u00f1o requeridos<\/li>\n<\/ul>\n<p>Los usos espec\u00edficos de las puertas telesc\u00f3picas:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/peatonales\/antipanico\/\">Puerta telesc\u00f3pica antip\u00e1nico (2 o 4 hojas)<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<hr \/>\n<h5>Puertas autom\u00e1ticas redondas, curvas y diedras<\/h5>\n<div style=\"padding-bottom: 50px;\">\n<div><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_configuration_ronde.jpg\" \/><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_configuration_cintree.jpg\" \/><\/div>\n<div>\n<p>Elegantes y funcionales, las puertas redondas, curvas y diedras permiten grandes radios de curvatura para entradas anchas, pero tambi\u00e9n profundas: las puertas redondas y curvas transforman una entrada en una recepci\u00f3n espaciosa y confortable.<\/p>\n<p><a href=\"https:\/\/www.portalp.com\/es\/soluciones\/puertas-automaticas\/peatonales\/redondas-curvas-y-angulares\/\">Descubra m\u00e1s sobre nuestras puertas autom\u00e1ticas redondas, curvas y diedros.<\/a><\/p>\n<\/div>\n<\/div>\n<div id=\"schemas-config\" style=\"display: flex;\">\n<div style=\"display: flex; flex-direction: column; align-items: center; justify-content: start; margin-right: 15px;\">\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Redondo<br \/>360\u00b0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/ronde-360.png\" \/><\/p>\n<\/div>\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Curvado<br \/>360\u00b0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/cintree-360.png\" \/><\/p>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; align-items: center; margin-right: 15px;\">\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Media ca\u00f1a<br \/>Convexo 180\u00b0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/demi-ronde-convexe-180.png\" \/><\/p>\n<\/div>\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Media ca\u00f1a<br \/>C\u00f3ncavo 180\u00b0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/demi-ronde-concave-180.png\" \/><\/p>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; align-items: center; margin-right: 15px;\">\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Curvado<br \/>Convexo 180\u00b0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/cintree-convexe-180.png\" \/><\/p>\n<\/div>\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Curvado<br \/>C\u00f3ncavo 180\u00b0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/cintree-concave-180.png\" \/><\/p>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; align-items: center; margin-right: 15px;\">\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Curvado<br \/>oblongo<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/cintree-oblong.png\" \/><\/p>\n<\/div>\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Oblongo<br \/><span style=\"color: #fff;\">&#8211;<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/oblong.png\" \/><\/p>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; align-items: center;\">\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Diedro<br \/>interior<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/09\/diedre-V-interieur.png\" \/><\/p>\n<\/div>\n<div class=\"config-wrap\">\n<p class=\"schem-desc\" style=\"padding-bottom: 1em;\">Diedro<br \/>exterior<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/09\/diedre-V-exterieur.png\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Instalaci\u00f3n&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-transform: uppercase; font-weight: bold; color: #005b94; margin-bottom: 15px;\">\u00bfCon o sin hojas fijas?<\/p>\n<div><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2025\/02\/picto-porte-avec-fixes-es.png\" \/><br \/><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2025\/02\/picto-porte-sans-fixes-es.png\" \/><\/div>\n<p style=\"text-transform: uppercase; font-weight: bold; color: #005b94; margin-bottom: 15px;\">Las diferentes configuraciones de instalaci\u00f3n<\/p>\n<div class=\"onglet-toggle closed-tab\">\n<h3>Entre paredes (empotrado en la pared)<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<p style=\"margin-bottom: 20px;\">Cuando una puerta se instala \u00abentre paredes\u00bb, esto significa que el mecanismo de la puerta, incluido el carril gu\u00eda y otros componentes, se empotra en el espesor de la pared.<\/p>\n<div style=\"display: flex; justify-content: space-between;\">\n<div style=\"width: 60%;\">\n<ul>\n<li style=\"font-weight: 600;\">Ventajas:\n<ul>\n<li>Aspecto limpio y est\u00e9tico<\/li>\n<li>Ahorro de espacio, ya que la puerta queda enrasada con la superficie de la pared<\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 600;\">Criterios arquitect\u00f3nicos:\n<ul>\n<li>Espesor de pared suficiente para alojar el mecanismo<\/li>\n<li>Espacio lateral disponible para el movimiento horizontal de la puerta<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"width: 35%;\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2025\/01\/picto-porte-entre-murs-v2.png\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"onglet-toggle closed-tab\">\n<h3>Montaje en aplique (fijado a la superficie de la pared)<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<p style=\"margin-bottom: 20px;\">Cuando una puerta se instala \u00aben superficie\u00bb, significa que el mecanismo de la puerta se fija directamente a la superficie de la pared. El carril gu\u00eda se monta en el exterior de la pared.<\/p>\n<div>\n<div>\n<ul>\n<li style=\"font-weight: 600;\">Ventajas:\n<ul>\n<li>F\u00e1cil de instalar, no requiere grandes obras en la estructura de la pared<\/li>\n<li>Flexibilidad para sustituir o mejorar las puertas existentes<\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 600;\">Criterios arquitect\u00f3nicos:\n<ul>\n<li>Superficie de la pared suficientemente resistente para soportar el peso de la puerta y el mecanismo<\/li>\n<li>Espacio disponible en la superficie de la pared para fijar el carril gu\u00eda<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<div><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-porte-sur-applique.png\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"onglet-toggle closed-tab\">\n<h3>En postes (montantes)<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-plus.png\" \/><\/p>\n<div class=\"onglet-toggle-content\">\n<p style=\"margin-bottom: 20px;\">Cuando una puerta se instala \u00absobre postes\u00bb, significa que el mecanismo de la puerta est\u00e1 montado sobre postes o montantes especiales en lugar de directamente en la pared. Estos postes act\u00faan como soporte de la estructura de la puerta.<\/p>\n<div>\n<div>\n<ul>\n<li style=\"font-weight: 600;\">Ventajas:\n<ul>\n<li>Flexibilidad en el dise\u00f1o y la disposici\u00f3n de la puerta<\/li>\n<li>Puede utilizarse cuando las condiciones de la pared no permiten la instalaci\u00f3n directa<\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 600;\">Criterios arquitect\u00f3nicos:\n<ul>\n<li>Postes s\u00f3lidos y bien anclados para soportar el mecanismo<\/li>\n<li>Distancia entre postes suficiente para permitir el movimiento de la puerta<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<div><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/06\/picto-porte-sur-poteaux.png\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_tab][\/et_pb_tabs][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEzMjkifX0=@&#8221; button_text=&#8221;Cont\u00e1ctenos&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||29px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Descubra nuestras soluciones<\/h2>\n<p>[\/et_pb_text][dica_divi_carousel item_width_tablet=&#8221;23%&#8221; item_width_phone=&#8221;75%&#8221; item_width_last_edited=&#8221;on|phone&#8221; arrow_nav=&#8221;on&#8221; dot_nav=&#8221;on&#8221; equal_height=&#8221;on&#8221; advanced_effect=&#8221;1&#8243; overlay_color_field_bgcolor=&#8221;rgba(255,255,255,0.85)&#8221; admin_label=&#8221;Carrousel solutions&#8221; module_class=&#8221;carousel-type-1&#8243; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; border_radii_image=&#8221;on|15px|15px|15px|15px&#8221; global_module=&#8221;7055&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][dica_divi_carouselitem admin_label=&#8221;All&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_rupture_pont_thermique_RPT_2.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE2NjcifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Todas nuestras<br \/>puertas autom\u00e1ticas<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Porte coulissante&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_coulissante_1.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjYzOSJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Puerta autom\u00e1tica<br \/>corredera<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Portes hospitali\u00e8res&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/portalp_porte_automatique_debit_fuite_controle_DL_Clean1.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjcwOTQifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Puertas de<br \/>hospital<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Portes rondes&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_ronde-1.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEyNDcwIn19@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Puertas autom\u00e1ticas<br \/>redondas y curvas<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Op\u00e9rateur porte battante&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/portalp_operateur_porte_battante_ISO3.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijg4ODIifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Operador de<br \/>puerta batiente<\/p>\n<p>[\/dica_divi_carouselitem][\/dica_divi_carousel][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||29px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Tus mercados<\/h2>\n<p>[\/et_pb_text][dica_divi_carousel item_width_tablet=&#8221;300px&#8221; item_width_phone=&#8221;270px&#8221; item_width_last_edited=&#8221;on|phone&#8221; loop=&#8221;on&#8221; arrow_nav=&#8221;on&#8221; dot_nav=&#8221;on&#8221; equal_height=&#8221;on&#8221; lazy_loading=&#8221;on&#8221; load_before_transition=&#8221;on&#8221; advanced_effect=&#8221;1&#8243; overlay_color_field_bgcolor=&#8221;rgba(255,255,255,0.85)&#8221; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Syndics &#8211; Copropri\u00e9t\u00e9s&#8221; module_class=&#8221;carousel-type-1&#8243; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; body_font=&#8221;|600|||||||&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_module=&#8221;7813&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][dica_divi_carouselitem admin_label=&#8221;Sites propres &#8211; Sites sensibles&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/salles-prores.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwMzkiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Salas limpias<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Sant\u00e9 &#8211; Hospitalier&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/sante-hospitalier-scaled.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijk4NzAiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Salud<br \/>Hospitales<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Cabinets d&#8217;architectes &#8211; Entreprises g\u00e9n\u00e9rales&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/archi-entreprise-generale.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4NzUiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Arquitectos <br \/>Contratistas generales<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Industries&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/industries.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjExNzU1IiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Industrias<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Secteur bancaire&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/bancaire.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEyMzM5IiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Sector bancario<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Administration et collectivit\u00e9s&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/administration-tertiaire.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; body_font=&#8221;|600|||||||&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4ODUiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Administraciones p\u00fablicas <br \/>Municipalidades<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Commerces&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/commerces.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; body_font=&#8221;|600|||||||&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4ODgiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Comercio<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Hotellerie &#8211; Restauration&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/hotellerie-restauration.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTEiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Hosteler\u00eda<br \/>Restauraci\u00f3n<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Transport ferroviaire&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/transport-ferroviaire.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE2NDEiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Transporte ferroviario<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8221;Syndics &#8211; Copropri\u00e9t\u00e9s&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/copropriete.jpg&#8221; _builder_version=&#8221;4.27.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTUiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Administradores de copropiedades<\/p>\n<p>[\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span><span><a href=\"https:\/\/www.portalp.com\/es\/\">Inicio<\/a><\/span><\/span>\u00bfC\u00f3mo elegir su puerta autom\u00e1tica?<div><div id=\"image-map-pro-f1b1c7be-258d-4c4d-9802-af249a724383\"><\/div><\/div> Grosor del relleno Gama de hojas Todos los tipos de 8 a 10,8 mm Todos los tipos de 13 a 15 mm Todos los tipos de 24 a 26 mm Todos los tipos 30 mm Doble acristalamiento de 34 a 36 mm Contraflam EI30 20 mm claro Contraflam EI30 20 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55848,"parent":37966,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-37955","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gu\u00eda de selecci\u00f3n | Portalp<\/title>\n<meta name=\"description\" content=\"Descubra c\u00f3mo funcionan las puertas autom\u00e1ticas con nuestra gu\u00eda de selecci\u00f3n e identifique la soluci\u00f3n ideal para sus necesidades\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda de selecci\u00f3n | Portalp\" \/>\n<meta property=\"og:description\" content=\"Descubra c\u00f3mo funcionan las puertas autom\u00e1ticas con nuestra gu\u00eda de selecci\u00f3n e identifique la soluci\u00f3n ideal para sus necesidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Portalp\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T13:31:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/picto-guide-choix-beige.png\" \/>\n\t<meta property=\"og:image:width\" content=\"220\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/\",\"name\":\"Gu\u00eda de selecci\u00f3n | Portalp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/picto-guide-choix-beige.png\",\"datePublished\":\"2024-05-13T11:23:34+00:00\",\"dateModified\":\"2025-07-23T13:31:05+00:00\",\"description\":\"Descubra c\u00f3mo funcionan las puertas autom\u00e1ticas con nuestra gu\u00eda de selecci\u00f3n e identifique la soluci\u00f3n ideal para sus necesidades\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/picto-guide-choix-beige.png\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/picto-guide-choix-beige.png\",\"width\":220,\"height\":245,\"caption\":\"picto guide de choix beige\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/guia-de-seleccion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Herramientas y medios\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/herramientas-y-medios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gu\u00eda de selecci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/\",\"name\":\"Portalp\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/#organization\",\"name\":\"Portalp\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"width\":375,\"height\":142,\"caption\":\"Portalp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/portalp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gu\u00eda de selecci\u00f3n | Portalp","description":"Descubra c\u00f3mo funcionan las puertas autom\u00e1ticas con nuestra gu\u00eda de selecci\u00f3n e identifique la soluci\u00f3n ideal para sus necesidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/","og_locale":"es_ES","og_type":"article","og_title":"Gu\u00eda de selecci\u00f3n | Portalp","og_description":"Descubra c\u00f3mo funcionan las puertas autom\u00e1ticas con nuestra gu\u00eda de selecci\u00f3n e identifique la soluci\u00f3n ideal para sus necesidades","og_url":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/","og_site_name":"Portalp","article_modified_time":"2025-07-23T13:31:05+00:00","og_image":[{"width":220,"height":245,"url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/picto-guide-choix-beige.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/","url":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/","name":"Gu\u00eda de selecci\u00f3n | Portalp","isPartOf":{"@id":"https:\/\/www.portalp.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/#primaryimage"},"image":{"@id":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/picto-guide-choix-beige.png","datePublished":"2024-05-13T11:23:34+00:00","dateModified":"2025-07-23T13:31:05+00:00","description":"Descubra c\u00f3mo funcionan las puertas autom\u00e1ticas con nuestra gu\u00eda de selecci\u00f3n e identifique la soluci\u00f3n ideal para sus necesidades","breadcrumb":{"@id":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/#primaryimage","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/picto-guide-choix-beige.png","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/03\/picto-guide-choix-beige.png","width":220,"height":245,"caption":"picto guide de choix beige"},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/guia-de-seleccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.portalp.com\/es\/"},{"@type":"ListItem","position":2,"name":"Herramientas y medios","item":"https:\/\/www.portalp.com\/es\/herramientas-y-medios\/"},{"@type":"ListItem","position":3,"name":"Gu\u00eda de selecci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.portalp.com\/es\/#website","url":"https:\/\/www.portalp.com\/es\/","name":"Portalp","description":"","publisher":{"@id":"https:\/\/www.portalp.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalp.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.portalp.com\/es\/#organization","name":"Portalp","url":"https:\/\/www.portalp.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.portalp.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","width":375,"height":142,"caption":"Portalp"},"image":{"@id":"https:\/\/www.portalp.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/portalp"]}]}},"_links":{"self":[{"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/pages\/37955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/comments?post=37955"}],"version-history":[{"count":0,"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/pages\/37955\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/pages\/37966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/media\/55848"}],"wp:attachment":[{"href":"https:\/\/www.portalp.com\/es\/wp-json\/wp\/v2\/media?parent=37955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}