{"id":25451,"date":"2023-12-14T08:34:10","date_gmt":"2023-12-14T07:34:10","guid":{"rendered":"https:\/\/www.portalp.com\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/"},"modified":"2025-01-24T10:57:02","modified_gmt":"2025-01-24T09:57:02","slug":"portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen","status":"publish","type":"post","link":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/","title":{"rendered":"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0.3) 0%|rgba(255,255,255,0) 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/09\/3-hommes-epi.jpg&#8220; height=&#8220;75vh&#8220; custom_margin=&#8220;110px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_text_shadow_style=&#8220;preset3&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen<\/h1>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/09\/iso-9001-45001.png&#8220; alt=&#8220;ISO 9001 45001&#8243; align=&#8220;center&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; width=&#8220;40%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Die Zertifizierungen ISO 9001 und 45001 legen die Anforderungen f\u00fcr Qualit\u00e4tsmanagementsysteme und f\u00fcr den Arbeits- und Gesundheitsschutz (AGS) fest. Diese Normen gelten f\u00fcr s\u00e4mtliche Aktivit\u00e4ten von Portalp, einschlie\u00dflich der Vermarktung, Installation und Wartung verschiedener Geb\u00e4udeschlie\u00dfsysteme sowie der Installation von Bahnsteigt\u00fcren. Sie best\u00e4tigen nicht nur die Einhaltung der betrieblichen Anforderungen in allen Portalp-Niederlassungen und im Werk, sondern auch die Dynamik des Verbesserungsprozesses auf nationaler Ebene. Das Zertifizierungsorgan bewertet au\u00dferdem das Engagement der Gesch\u00e4ftsleitung in Bezug auf Kundenzufriedenheit und Risikopr\u00e4vention f\u00fcr die Mitarbeiter.   <\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 style=\"text-align: left;\">Drei gepr\u00fcfte Niederlassungen<\/h2>\n<p>In diesem Jahr wurden die Niederlassungen in Azay-le-Br\u00fbl\u00e9, Pleyben und Cormelles-le-Royal im Rahmen des ersten Follow-ups der ISO 9001 und 45001 Zertifizierungen auditiert. Diese Audits erm\u00f6glichten es, die Konformit\u00e4t und Wirksamkeit der bestehenden Managementsysteme zu \u00fcberpr\u00fcfen. Sie zeigen, dass die Anforderungen an Qualit\u00e4t sowie Gesundheit und Sicherheit am Arbeitsplatz sowohl auf den Standorten als auch in den Zentraldiensten eingehalten werden. Die Teams haben ihr Engagement f\u00fcr die Prinzipien der Qualit\u00e4t und Arbeitssicherheit unter Beweis gestellt, was zu einer positiven Empfehlung f\u00fcr die Aufrechterhaltung der Zertifizierungen f\u00fchrte.   <\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 style=\"text-align: left;\">Ein Kunden Vorteil<\/h2>\n<p>Die Aufrechterhaltung der ISO 9001 und 45001 Zertifizierungen st\u00e4rkt das Vertrauen der Kunden in Portalp. Sie garantiert nicht nur die Qualit\u00e4t der gelieferten Produkte und Dienstleistungen, sondern auch die Umsetzung von Pr\u00e4ventionsma\u00dfnahmen auf allen Baustellen und in den verschiedenen Projektphasen, um ein sicheres und gesundes Arbeitsumfeld f\u00fcr die Mitarbeiter zu gew\u00e4hrleisten. Portalp bleibt fest entschlossen, seine Managementmethoden zu bewahren und weiter zu verbessern, um die hohen Erwartungen seiner Kunden zu erf\u00fcllen und aktiv zur F\u00f6rderung der besten Praktiken in seiner Branche beizutragen.  <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1ODU0In19@&#8220; button_text=&#8220;Hier finden Sie unsere Zertifizierungen&#8220; _builder_version=&#8220;4.24.2&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die ISO 9001 und 45001 Zertifizierungen best\u00e4tigen das Engagement von Portalp f\u00fcr Qualit\u00e4t, Sicherheit und Pr\u00e4vention auf all seinen Baustellen und gew\u00e4hrleisten seinen Kunden zuverl\u00e4ssige L\u00f6sungen und ein sicheres Arbeitsumfeld.<\/p>\n","protected":false},"author":1,"featured_media":16448,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[188],"tags":[],"class_list":["post-25451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-de_at"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen | Portalp<\/title>\n<meta name=\"description\" content=\"Portalp st\u00e4rkt Qualit\u00e4t und Sicherheit durch ISO 9001 und 45001. Engagement f\u00fcr Pr\u00e4vention, Kundenzufriedenheit und kontinuierliche Verbesserung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen | Portalp\" \/>\n<meta property=\"og:description\" content=\"Portalp st\u00e4rkt Qualit\u00e4t und Sicherheit durch ISO 9001 und 45001. Engagement f\u00fcr Pr\u00e4vention, Kundenzufriedenheit und kontinuierliche Verbesserung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Portalp\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T07:34:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T09:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2023\/12\/3-hommes-epi-une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TeamWeb_Jeremie-M\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"TeamWeb_Jeremie-M\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/\"},\"author\":{\"name\":\"TeamWeb_Jeremie-M\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#\\\/schema\\\/person\\\/78d6e12af2cb2f771000ddd42ac8135c\"},\"headline\":\"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen\",\"datePublished\":\"2023-12-14T07:34:10+00:00\",\"dateModified\":\"2025-01-24T09:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/\"},\"wordCount\":562,\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-hommes-epi-une.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"de-AT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/\",\"name\":\"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen | Portalp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-hommes-epi-une.jpg\",\"datePublished\":\"2023-12-14T07:34:10+00:00\",\"dateModified\":\"2025-01-24T09:57:02+00:00\",\"description\":\"Portalp st\u00e4rkt Qualit\u00e4t und Sicherheit durch ISO 9001 und 45001. Engagement f\u00fcr Pr\u00e4vention, Kundenzufriedenheit und kontinuierliche Verbesserung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-hommes-epi-une.jpg\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-hommes-epi-une.jpg\",\"width\":1280,\"height\":800,\"caption\":\"3 hommes avec des epi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#website\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/\",\"name\":\"Portalp\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#organization\",\"name\":\"Portalp\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"width\":375,\"height\":142,\"caption\":\"Portalp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/portalp\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de_AT\\\/#\\\/schema\\\/person\\\/78d6e12af2cb2f771000ddd42ac8135c\",\"name\":\"TeamWeb_Jeremie-M\",\"sameAs\":[\"https:\\\/\\\/www.portalp.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen | Portalp","description":"Portalp st\u00e4rkt Qualit\u00e4t und Sicherheit durch ISO 9001 und 45001. Engagement f\u00fcr Pr\u00e4vention, Kundenzufriedenheit und kontinuierliche Verbesserung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/","og_locale":"de_DE","og_type":"article","og_title":"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen | Portalp","og_description":"Portalp st\u00e4rkt Qualit\u00e4t und Sicherheit durch ISO 9001 und 45001. Engagement f\u00fcr Pr\u00e4vention, Kundenzufriedenheit und kontinuierliche Verbesserung.","og_url":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/","og_site_name":"Portalp","article_published_time":"2023-12-14T07:34:10+00:00","article_modified_time":"2025-01-24T09:57:02+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2023\/12\/3-hommes-epi-une.jpg","type":"image\/jpeg"}],"author":"TeamWeb_Jeremie-M","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"TeamWeb_Jeremie-M","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/#article","isPartOf":{"@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/"},"author":{"name":"TeamWeb_Jeremie-M","@id":"https:\/\/www.portalp.com\/de_AT\/#\/schema\/person\/78d6e12af2cb2f771000ddd42ac8135c"},"headline":"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen","datePublished":"2023-12-14T07:34:10+00:00","dateModified":"2025-01-24T09:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/"},"wordCount":562,"publisher":{"@id":"https:\/\/www.portalp.com\/de_AT\/#organization"},"image":{"@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2023\/12\/3-hommes-epi-une.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"de-AT"},{"@type":"WebPage","@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/","url":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/","name":"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen | Portalp","isPartOf":{"@id":"https:\/\/www.portalp.com\/de_AT\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/#primaryimage"},"image":{"@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2023\/12\/3-hommes-epi-une.jpg","datePublished":"2023-12-14T07:34:10+00:00","dateModified":"2025-01-24T09:57:02+00:00","description":"Portalp st\u00e4rkt Qualit\u00e4t und Sicherheit durch ISO 9001 und 45001. Engagement f\u00fcr Pr\u00e4vention, Kundenzufriedenheit und kontinuierliche Verbesserung.","breadcrumb":{"@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/#primaryimage","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2023\/12\/3-hommes-epi-une.jpg","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2023\/12\/3-hommes-epi-une.jpg","width":1280,"height":800,"caption":"3 hommes avec des epi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalp.com\/de_AT\/portalp-erneuert-seine-iso-9001-und-45001-zertifizierungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.portalp.com\/de_AT\/"},{"@type":"ListItem","position":2,"name":"Portalp erneuert seine ISO 9001 und 45001 Zertifizierungen"}]},{"@type":"WebSite","@id":"https:\/\/www.portalp.com\/de_AT\/#website","url":"https:\/\/www.portalp.com\/de_AT\/","name":"Portalp","description":"","publisher":{"@id":"https:\/\/www.portalp.com\/de_AT\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalp.com\/de_AT\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"},{"@type":"Organization","@id":"https:\/\/www.portalp.com\/de_AT\/#organization","name":"Portalp","url":"https:\/\/www.portalp.com\/de_AT\/","logo":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.portalp.com\/de_AT\/#\/schema\/logo\/image\/","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","width":375,"height":142,"caption":"Portalp"},"image":{"@id":"https:\/\/www.portalp.com\/de_AT\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/portalp"]},{"@type":"Person","@id":"https:\/\/www.portalp.com\/de_AT\/#\/schema\/person\/78d6e12af2cb2f771000ddd42ac8135c","name":"TeamWeb_Jeremie-M","sameAs":["https:\/\/www.portalp.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/posts\/25451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/comments?post=25451"}],"version-history":[{"count":0,"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/posts\/25451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/media\/16448"}],"wp:attachment":[{"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/media?parent=25451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/categories?post=25451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalp.com\/de_AT\/wp-json\/wp\/v2\/tags?post=25451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}