{"id":30926,"date":"2024-12-13T10:47:15","date_gmt":"2024-12-13T09:47:15","guid":{"rendered":"https:\/\/www.portalp.com\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/"},"modified":"2024-12-13T16:48:54","modified_gmt":"2024-12-13T15:48:54","slug":"automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden","status":"publish","type":"post","link":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/","title":{"rendered":"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;110px||110px||true|false&#8220; custom_margin_tablet=&#8220;110px||||false|false&#8220; custom_margin_phone=&#8220;70px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_text_color=&#8220;#005B94&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1 style=\"text-align: center;\">Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/12\/femme-devant-vitrine-1.jpg&#8220; alt=&#8220;Frau beim Einkaufen vor einem Schaufenster&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Mit der Ankunft des Winters werden automatische T\u00fcren zu unverzichtbaren Verb\u00fcndeten f\u00fcr Unternehmen, die den Komfort in ihren R\u00e4umen optimieren und gleichzeitig den <strong>Energieverbrauch senken m\u00f6chten<\/strong>. Diese Anlagen bieten nicht nur einen praktischen Durchgang mit ber\u00fchrungslosem \u00d6ffnen, sondern tragen auch aktiv zu einem nachhaltigen Energiemanagement bei, insbesondere in der Winterzeit. <\/p>\n<p>Durch einen <strong>sparsamen Umgang mit Energie<\/strong>, den vern\u00fcnftigen Einsatz von Ger\u00e4ten und die Vermeidung von Verschwendung k\u00f6nnen Unternehmen und Privatpersonen ihren <strong>Energieverbrauch und ihre Ausgaben senken<\/strong>. Das Bewusstsein f\u00fcr einen sparsameren Umgang mit Energie w\u00e4chst und verdeutlicht einen Wandel hin zu verantwortungsvolleren Praktiken. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#E4DAD3&#8243; width=&#8220;100%&#8220; max_width=&#8220;100%&#8220; custom_margin=&#8220;32px|auto|31px|auto||&#8220; custom_padding=&#8220;29px|20px|29px|20px|true|true&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||21px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p style=\"text-align: center;\">Haben Sie Lust, <strong>den Komfort Ihrer R\u00e4ume zu optimieren<\/strong> und <strong>gleichzeitig Ihren Energieverbrauch zu senken<\/strong>?<\/p>\n<p style=\"text-align: center;\">Kontaktieren Sie uns noch heute, um unsere ma\u00dfgeschneiderten L\u00f6sungen f\u00fcr automatische T\u00fcren kennenzulernen.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQxNDMifX0=@&#8220; button_text=&#8220;Kontakte&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>In dieser Herausforderung spielen automatische T\u00fcren eine grundlegende Rolle, dank ihrer technologischen Innovationen, die Komfort, Energieeinsparung und Umweltfreundlichkeit miteinander verbinden. Sie sind nun so konzipiert, dass sie den aktuellen Herausforderungen der <strong>Energieeffizienz <\/strong>gerecht werden, indem sie praktische L\u00f6sungen f\u00fcr Gesch\u00e4fts- und Industriegeb\u00e4ude bieten: <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;|145px||auto||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;20px&#8220; custom_padding=&#8220;15px|10px|15px|10px|true|true&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;on|15px|15px|15px|15px&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_color=&#8220;rgba(0,0,0,0.1)&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2>Erweiterte Einstellungen<\/h2>\n<p>Unsere T\u00fcren lassen sich dank intuitiver Apps ganz einfach per Smartphone einstellen.<\/p>\n<p>Mit wenigen Klicks ist es m\u00f6glich, die Geschwindigkeit und die Breite der \u00d6ffnung nach Bedarf anzupassen, wodurch der W\u00e4rmeverlust reduziert wird.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;20px&#8220; custom_padding=&#8220;15px|10px|15px|10px|true|true&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_color=&#8220;rgba(0,0,0,0.1)&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Intelligente Erkennung<\/h2>\n<p>Dank leistungsf\u00e4higer Erkennungssysteme \u00f6ffnen sich die T\u00fcren nur, wenn ein Nutzer anwesend ist, wodurch ungewollte \u00d6ffnungen vermieden werden.<\/p>\n<p>Unidirektionale Melder sind in der Lage, die Bewegungsrichtung von Personen zu erkennen. Dadurch kann sich die T\u00fcr nur dann \u00f6ffnen, wenn sich jemand in der vorgesehenen Richtung n\u00e4hert (z. B. hinein oder hinaus), wodurch unn\u00f6tige \u00d6ffnungen vermieden werden, die zu unn\u00f6tigen \u00d6ffnungen und damit zu Energieverlusten f\u00fchren k\u00f6nnten. <\/p>\n<p>Die genaue Einstellung der Melder ist entscheidend, um unn\u00f6tige \u00d6ffnungen zu vermeiden. Unsere Techniker stellen sie sorgf\u00e4ltig ein und optimieren die Erfassungsbereiche, um unerw\u00fcnschte \u00d6ffnungen zu vermeiden und eine maximale Effizienz zu gew\u00e4hrleisten, die an jede Umgebung angepasst ist. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;20px&#8220; custom_padding=&#8220;15px|10px|15px|10px|true|true&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_color=&#8220;rgba(0,0,0,0.1)&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Maximale Transparenz<\/h2>\n<p>Die T\u00fcren sind mit Glasfl\u00fcgeln ausgestattet, die eine gro\u00dfe Helligkeit der Bucht bieten und die Zufuhr von nat\u00fcrlichem Licht in allen R\u00e4umen f\u00f6rdern. Sie reduzieren unweigerlich den Bedarf an k\u00fcnstlicher Beleuchtung w\u00e4hrend des Tages und tragen dazu bei, den Stromverbrauch zu senken. <\/p>\n<p>Die thermische Leistung von Verglasungen wird immer besser, da sie immer besser isolieren und so f\u00fcr mehr Komfort in den R\u00e4umen sorgen, den W\u00e4rmeverlust vor allem in der Nacht einschr\u00e4nken und letztendlich ein besseres Energiemanagement gew\u00e4hrleisten.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;20px&#8220; custom_padding=&#8220;15px|10px|15px|10px|true|true&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_color=&#8220;rgba(0,0,0,0.1)&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Sorgf\u00e4ltige Abdichtung<\/h2>\n<p>Die Dichtungen rund um die Fl\u00fcgel sorgen f\u00fcr eine relative Dichtigkeit, die das Eindringen von kalter Luft verhindert, wodurch die Innentemperatur erhalten bleibt und die Notwendigkeit, die R\u00e4ume st\u00e4ndig zu erw\u00e4rmen, reduziert wird.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|||20px|false|false&#8220; border_width_left=&#8220;5px&#8220; border_color_left=&#8220;#E4DAD3&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Diese technischen Vorteile erm\u00f6glichen es, durch bewusste Entscheidungen Energie zu sparen und gleichzeitig den Komfort und die Sicherheit der Nutzer zu gew\u00e4hrleisten. Automatische T\u00fcren tragen ebenso wie andere Ausr\u00fcstungen zu einem verantwortungsvolleren Umgang mit Energie f\u00fcr eine nachhaltige Zukunft bei. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;2_5,3_5&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#E4DAD3&#8243; overflow-x=&#8220;visible&#8220; overflow-y=&#8220;visible&#8220; custom_margin=&#8220;20px||||false|false&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|true&#8220; border_radii=&#8220;on|30px|30px|30px|30px&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/portalp_porte_automatique_rupture_pont_thermique_RPT_2.jpg&#8220; alt=&#8220;Automatische T\u00fcr mit W\u00e4rmetrennung&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; positioning=&#8220;absolute&#8220; width=&#8220;100%&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;30px||30px||true|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Optimieren Sie die Energieeffizienz Ihrer Geb\u00e4ude mit unserer thermisch getrennten Automatikt\u00fcr.<\/p>\n<p>Sie wurde entwickelt, um W\u00e4rmeverluste zu reduzieren und die Isolierung zu verbessern. Sie sorgt f\u00fcr optimalen Komfort und verringert gleichzeitig die Auswirkungen auf die Umwelt.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjUxODkifX0=@&#8220; button_text=&#8220;Entdecken Sie sie hier&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Optimieren Sie diesen Winter Komfort und Energie mit automatischen T\u00fcren: Innovationen, Dichtheit und intelligente Erkennung verbinden Bequemlichkeit und Nachhaltigkeit.<\/p>\n","protected":false},"author":1,"featured_media":30841,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[185],"tags":[],"class_list":["post-30926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden | Portalp<\/title>\n<meta name=\"description\" content=\"Entscheiden Sie sich f\u00fcr innovative automatische T\u00fcren, die Ihnen in diesem Winter optimalen Komfort und Energieeinsparungen bieten. Entdecken Sie jetzt unsere nachhaltigen L\u00f6sungen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden | Portalp\" \/>\n<meta property=\"og:description\" content=\"Entscheiden Sie sich f\u00fcr innovative automatische T\u00fcren, die Ihnen in diesem Winter optimalen Komfort und Energieeinsparungen bieten. Entdecken Sie jetzt unsere nachhaltigen L\u00f6sungen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/\" \/>\n<meta property=\"og:site_name\" content=\"Portalp\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-13T09:47:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T15:48:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/12\/femme-devant-vitrine-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TeamWeb_Jeremie-M\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"TeamWeb_Jeremie-M\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/\"},\"author\":{\"name\":\"TeamWeb_Jeremie-M\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#\\\/schema\\\/person\\\/78d6e12af2cb2f771000ddd42ac8135c\"},\"headline\":\"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden\",\"datePublished\":\"2024-12-13T09:47:15+00:00\",\"dateModified\":\"2024-12-13T15:48:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/\"},\"wordCount\":1395,\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/femme-devant-vitrine-1.jpg\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/\",\"name\":\"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden | Portalp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/femme-devant-vitrine-1.jpg\",\"datePublished\":\"2024-12-13T09:47:15+00:00\",\"dateModified\":\"2024-12-13T15:48:54+00:00\",\"description\":\"Entscheiden Sie sich f\u00fcr innovative automatische T\u00fcren, die Ihnen in diesem Winter optimalen Komfort und Energieeinsparungen bieten. Entdecken Sie jetzt unsere nachhaltigen L\u00f6sungen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/femme-devant-vitrine-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/femme-devant-vitrine-1.jpg\",\"width\":750,\"height\":500,\"caption\":\"Femme faisant du shopping devant une vitrine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/\",\"name\":\"Portalp\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#organization\",\"name\":\"Portalp\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"width\":375,\"height\":142,\"caption\":\"Portalp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/portalp\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#\\\/schema\\\/person\\\/78d6e12af2cb2f771000ddd42ac8135c\",\"name\":\"TeamWeb_Jeremie-M\",\"sameAs\":[\"https:\\\/\\\/www.portalp.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden | Portalp","description":"Entscheiden Sie sich f\u00fcr innovative automatische T\u00fcren, die Ihnen in diesem Winter optimalen Komfort und Energieeinsparungen bieten. Entdecken Sie jetzt unsere nachhaltigen L\u00f6sungen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/","og_locale":"de_DE","og_type":"article","og_title":"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden | Portalp","og_description":"Entscheiden Sie sich f\u00fcr innovative automatische T\u00fcren, die Ihnen in diesem Winter optimalen Komfort und Energieeinsparungen bieten. Entdecken Sie jetzt unsere nachhaltigen L\u00f6sungen!","og_url":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/","og_site_name":"Portalp","article_published_time":"2024-12-13T09:47:15+00:00","article_modified_time":"2024-12-13T15:48:54+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/12\/femme-devant-vitrine-1.jpg","type":"image\/jpeg"}],"author":"TeamWeb_Jeremie-M","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"TeamWeb_Jeremie-M","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/#article","isPartOf":{"@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/"},"author":{"name":"TeamWeb_Jeremie-M","@id":"https:\/\/www.portalp.com\/de\/#\/schema\/person\/78d6e12af2cb2f771000ddd42ac8135c"},"headline":"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden","datePublished":"2024-12-13T09:47:15+00:00","dateModified":"2024-12-13T15:48:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/"},"wordCount":1395,"publisher":{"@id":"https:\/\/www.portalp.com\/de\/#organization"},"image":{"@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/12\/femme-devant-vitrine-1.jpg","articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/","url":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/","name":"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden | Portalp","isPartOf":{"@id":"https:\/\/www.portalp.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/#primaryimage"},"image":{"@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/12\/femme-devant-vitrine-1.jpg","datePublished":"2024-12-13T09:47:15+00:00","dateModified":"2024-12-13T15:48:54+00:00","description":"Entscheiden Sie sich f\u00fcr innovative automatische T\u00fcren, die Ihnen in diesem Winter optimalen Komfort und Energieeinsparungen bieten. Entdecken Sie jetzt unsere nachhaltigen L\u00f6sungen!","breadcrumb":{"@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/#primaryimage","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/12\/femme-devant-vitrine-1.jpg","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/12\/femme-devant-vitrine-1.jpg","width":750,"height":500,"caption":"Femme faisant du shopping devant une vitrine"},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalp.com\/de\/automatische-tueren-sind-ein-schluesselfaktor-um-im-winter-komfort-und-energiesparen-miteinander-zu-verbinden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.portalp.com\/de\/"},{"@type":"ListItem","position":2,"name":"Automatische T\u00fcren sind ein Schl\u00fcsselfaktor, um im Winter Komfort und Energiesparen miteinander zu verbinden"}]},{"@type":"WebSite","@id":"https:\/\/www.portalp.com\/de\/#website","url":"https:\/\/www.portalp.com\/de\/","name":"Portalp","description":"","publisher":{"@id":"https:\/\/www.portalp.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalp.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.portalp.com\/de\/#organization","name":"Portalp","url":"https:\/\/www.portalp.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.portalp.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","width":375,"height":142,"caption":"Portalp"},"image":{"@id":"https:\/\/www.portalp.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/portalp"]},{"@type":"Person","@id":"https:\/\/www.portalp.com\/de\/#\/schema\/person\/78d6e12af2cb2f771000ddd42ac8135c","name":"TeamWeb_Jeremie-M","sameAs":["https:\/\/www.portalp.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/posts\/30926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/comments?post=30926"}],"version-history":[{"count":0,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/posts\/30926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/media\/30841"}],"wp:attachment":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/media?parent=30926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/categories?post=30926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/tags?post=30926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}