{"id":18637,"date":"2024-04-12T13:18:42","date_gmt":"2024-04-12T12:18:42","guid":{"rendered":"https:\/\/www.portalp.com\/einsatzbereiche\/hotel-und-gaststaettengewerbe\/"},"modified":"2025-10-17T15:59:51","modified_gmt":"2025-10-17T14:59:51","slug":"gastgewerbe-restaurants","status":"publish","type":"page","link":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/","title":{"rendered":"Gastgewerbe &#038; Restaurants"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(0,0,0,0.34) 0%|rgba(41,196,169,0) 60%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/09\/restaurant-cafe.jpg&#8220; height=&#8220;75vh&#8220; custom_margin=&#8220;110px||||false|false&#8220; custom_margin_tablet=&#8220;110px||||false|false&#8220; custom_margin_phone=&#8220;70px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;||||true|false&#8220; custom_padding_tablet=&#8220;8%||8%||true|false&#8220; custom_padding_phone=&#8220;5%||5%||true|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_margin_tablet=&#8220;||||false|false&#8220; custom_margin_phone=&#8220;15%|auto||auto|false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;0px||0px||true|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.2&#8243; _module_preset=&#8220;default&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;30px&#8220; header_font=&#8220;|700|||||||&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||0px||false|false&#8220; text_text_shadow_style=&#8220;preset3&#8243; text_text_shadow_blur_strength=&#8220;0.74em&#8220; text_text_shadow_color=&#8220;#000000&#8243; header_text_shadow_style=&#8220;preset3&#8243; header_text_shadow_color=&#8220;#000000&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>Gastgewerbe &amp; Restaurants<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;25px&#8220; text_orientation=&#8220;center&#8220; text_text_shadow_style=&#8220;preset3&#8243; text_text_shadow_blur_strength=&#8220;0.74em&#8220; text_text_shadow_color=&#8220;#000000&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Verbesserte Kundenerfahrung und optimierte betriebliche Effizienz<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;2_5,3_5&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|600|||||||&#8220; text_text_color=&#8220;#005B94&#8243; text_line_height=&#8220;1.4em&#8220; background_color=&#8220;rgba(255,255,255,0.9)&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|true&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; box_shadow_style=&#8220;preset3&#8243; box_shadow_color=&#8220;RGBA(255,255,255,0)&#8220; box_shadow_color_tablet=&#8220;RGBA(255,255,255,0)&#8220; box_shadow_color_phone=&#8220;rgba(0,0,0,0.1)&#8220; box_shadow_color_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Von der Installation automatischer T\u00fcren am Empfang und in der K\u00fcche \u00fcber die Verwaltung der Parkplatzzufahrten bis hin zur Sicherung Ihrer Geb\u00e4ude &#8211; mit unseren Produktl\u00f6sungen richten wir uns nach Ihren Bed\u00fcrfnissen. <\/p>\n<p>Damit k\u00f6nnen Sie sich auf das Wesentliche konzentrieren: die Bewirtung Ihrer G\u00e4ste.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEzMjkifX0=@&#8220; button_text=&#8220;Kontaktieren Sie uns!&#8220; _builder_version=&#8220;4.24.2&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; button_border_width=&#8220;5px&#8220; button_border_color=&#8220;#FFFFFF&#8220; transform_scale_tablet=&#8220;&#8220; transform_scale_phone=&#8220;&#8220; transform_scale_last_edited=&#8220;on|phone&#8220; transform_translate=&#8220;0px|-50%&#8220; transform_translate_tablet=&#8220;0px|-50%&#8220; transform_translate_phone=&#8220;0px|0%&#8220; transform_translate_last_edited=&#8220;on|phone&#8220; transform_translate_linked=&#8220;off&#8220; transform_rotate_tablet=&#8220;&#8220; transform_rotate_phone=&#8220;&#8220; transform_rotate_last_edited=&#8220;on|phone&#8220; transform_skew_tablet=&#8220;&#8220; transform_skew_phone=&#8220;&#8220; transform_skew_last_edited=&#8220;on|phone&#8220; transform_origin_tablet=&#8220;&#8220; transform_origin_phone=&#8220;&#8220; transform_origin_last_edited=&#8220;on|phone&#8220; transform_styles_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;15px||15px||true|false&#8220; transform_styles_tablet=&#8220;&#8220; transform_styles_phone=&#8220;&#8220; global_colors_info=&#8220;{}&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#FFFFFF&#8220;][\/et_pb_button][et_pb_text disabled_on=&#8220;on|off|off&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; text_font_size=&#8220;0.8em&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<span><span><a href=\"https:\/\/www.portalp.com\/de\/\">Startseite<\/a><\/span><\/span>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|600|||||||&#8220; text_text_color=&#8220;#005B94&#8243; text_line_height=&#8220;1.4em&#8220; text_orientation=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Bei Portalp begleiten wir Fachleute aus dem Hotel- und Gastst\u00e4ttengewerbe bei der Optimierung des Kundenerlebnisses: Empfang, leichter Zutritt, Sicherheit.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;|auto|41px|auto||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dica_divi_carousel show_items_desktop=&#8220;3&#8243; arrow_nav=&#8220;on&#8220; dot_nav=&#8220;on&#8220; item_spacing=&#8220;50&#8243; equal_height=&#8220;on&#8220; advanced_effect=&#8220;1&#8243; overlay_color_field_bgcolor=&#8220;rgba(255,255,255,0.85)&#8220; carousel_container_padding=&#8220;||||false|false&#8220; innercontent_padding=&#8220;||||false|false&#8220; item_padding=&#8220;20px|20px|20px|20px|true|true&#8220; image_container_padding=&#8220;|30%|30px|30%|false|true&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; body_text_align=&#8220;center&#8220; body_text_color=&#8220;#FFFFFF&#8220; global_colors_info=&#8220;{}&#8220;][dica_divi_carouselitem title=&#8220;Senkung der Energiekosten&#8220; admin_label=&#8220;R\u00e9duction des co\u00fbts&#8220; button_url_new_window=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|600||on|||||&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;24px&#8220; header_line_height=&#8220;1.3em&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;#B49988&#8243; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Sch\u00fctzen Sie sich vor W\u00e4rme- oder K\u00e4lteverlusten, indem Sie das \u00d6ffnen und Schlie\u00dfen Ihrer T\u00fcr automatisch steuern und Zugluft reduzieren.<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8220;\u00c4sthetik nach Ma\u00df&#8220; admin_label=&#8220;Conformit\u00e9 aux normes&#8220; button_url_new_window=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|600||on|||||&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;24px&#8220; header_line_height=&#8220;1.3em&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;#B49988&#8243; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Da unsere automatischen T\u00fcren nach Ma\u00df entworfen werden, f\u00fcgen sie sich perfekt in die Geb\u00e4udearchitektur ein. Sie bestimmen selbst, in welchem Farbton, mit welchen Materialien, mit welcher F\u00fcllung und mit welchen Optionen sie ausgestattet werden sollen.<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8220;Optimale Barrierefreiheit&#8220; admin_label=&#8220;Ergonomie&#8220; button_url_new_window=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|600||on|||||&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;24px&#8220; header_line_height=&#8220;1.3em&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;#B49988&#8243; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Erleichtern Sie den Zugang f\u00fcr alle Ihre Kunden, auch f\u00fcr solche mit eingeschr\u00e4nkter Mobilit\u00e4t oder mit Gep\u00e4ck und Kinderwagen. Unsere automatischen T\u00fcren entsprechen den Richtlinien f\u00fcr Barrierfreiheit.<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8220;Einfache Bedienung&#8220; admin_label=&#8220;Conformit\u00e9 aux normes&#8220; button_url_new_window=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|600||on|||||&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;24px&#8220; header_line_height=&#8220;1.3em&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;#B49988&#8243; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Dank modernster Technologie sind unsere T\u00fcren einfach zu bedienen: Steuerung per Smartphone, Analyse von Fehlfunktionen, Verwaltung der Betriebsparameter usw.<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8220;Verst\u00e4rkte Sicherheit&#8220; admin_label=&#8220;Conformit\u00e9 aux normes&#8220; button_url_new_window=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|600||on|||||&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;24px&#8220; header_line_height=&#8220;1.3em&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;#B49988&#8243; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Dank unseres umfassenden Angebots k\u00f6nnen Sie den Zugang zu Ihrer Einrichtung und Ihrem Parkplatz kontrollieren. F\u00fcr eine optimale Sicherheit kann ein Zugangskontrollsystem an Ihre T\u00fcr installiert werden.<\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8220;Schneller Wartungsservice&#8220; admin_label=&#8220;Conformit\u00e9 aux normes&#8220; button_url_new_window=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|600||on|||||&#8220; header_text_align=&#8220;center&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;24px&#8220; header_line_height=&#8220;1.3em&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;#B49988&#8243; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Unsere fachkundigen Techniker bieten einen schnellen und individuellen Wartungsservice, der eine maximale Verf\u00fcgbarkeit Ihrer automatischen T\u00fcren und einen konstanten Zugang zu Ihrer Infrastruktur gew\u00e4hrleistet.<\/p>\n<p>[\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8220;information-legale&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#E4DAD3&#8243; custom_padding=&#8220;20px|20px|20px|20px|true|true&#8220; border_radii=&#8220;on|20px|20px|20px|20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/08\/picto-information.png\"><!-- [et_pb_line_break_holder] --><pee><!-- [et_pb_line_break_holder] -->  <strong>Manuelle oder automatische T\u00fcr: Wie hoch sind die Einsparungen beim Energieverbrauch?<\/strong><!\u2013- [et_pb_br_holder] -\u2013> Der Einbau einer automatischen T\u00fcrsteuerung bringt im Vergleich zu einer manuellen Steuerung (Heizung und Klimaanlage) eine durchschnittliche Einsparung von 10 %:<!\u2013- [et_pb_br_holder] -\u2013> <!-- [et_pb_line_break_holder] -->Der Wechsel zu einem automatischen Schlie\u00dfmechanismus senkt den Heizbedarf je nach Stadt um 7% bis 11%.<!\u2013- [et_pb_br_holder] -\u2013>In Hitzeperioden verringert dies auch den K\u00fchlbedarf und die unangenehme Tageszeit, wenn die Temperaturen 26\u00b0C oder 28\u00b0C \u00fcberschreiten.<!-- [et_pb_line_break_holder] --><!\u2013- [et_pb_br_holder] -\u2013> <strong>Thermische Studie zu automatischen T\u00fcren &#8211; unabh\u00e4ngige Studie Actibaie 2024<\/strong><!-- [et_pb_line_break_holder] --><\/pee>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#E4DAD3&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row disabled_on=&#8220;on|on|on&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; width_tablet=&#8220;&#8220; width_phone=&#8220;&#8220; width_last_edited=&#8220;on|phone&#8220; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Entdecken Sie unsere automatisierten Zugangsl\u00f6sungen f\u00fcr den Gastronomiebereich:<\/h2>\n<p>[\/et_pb_text][dica_divi_carousel item_width_tablet=&#8220;23%&#8220; item_width_phone=&#8220;75%&#8220; item_width_last_edited=&#8220;on|phone&#8220; show_items_desktop=&#8220;3&#8243; arrow_nav=&#8220;on&#8220; dot_nav=&#8220;on&#8220; equal_height=&#8220;on&#8220; advanced_effect=&#8220;1&#8243; overlay_color_field_bgcolor=&#8220;rgba(255,255,255,0.85)&#8220; content_container_padding=&#8220;15px|15px|15px|15px|true|true&#8220; module_id=&#8220;solutions-salles-propres&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; body_text_color=&#8220;#706F6F&#8220; global_colors_info=&#8220;{}&#8220;][dica_divi_carouselitem admin_label=&#8220;PAP&#8220; button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/pages_portes_automatiques_portes_pietonnes.jpg&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Automatische Fu\u00dfg\u00e4ngert\u00fcren<\/h3>\n<hr \/>\n<p>Speziell f\u00fcr anspruchsvolle Umgebungen entwickelt, sorgen sie f\u00fcr eine kontrollierte Lenkung der Personenstr\u00f6me und erh\u00f6hen gleichzeitig die Sicherheit durch erweiterte Optionen f\u00fcr die Zugangskontrolle.<\/p>\n<ul>\n<li>Optimale Lenkung der Personenstr\u00f6me<\/li>\n<li>Erh\u00f6hte Sicherheit durch Einbruchschutzsysteme<\/li>\n<li>Maximaler Komfort f\u00fcr Ihre G\u00e4ste<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.portalp.com\/solutions\/portes-automatiques\/portes-automatiques-pietonnes\/\">Mehr erfahren<\/a><\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8220;Acc\u00e8s parking&#8220; button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/portalp_porte_automatique_etanche_HDS_Clean-1.jpg&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;#FFFFFF&#8220; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Parkplatzzufahrten<\/h3>\n<hr \/>\n<p>Verschaffen Sie Ihren Mitarbeitern und Kunden mit unseren Zugangssystemen einen leichteren Zugang zu Ihren Parkpl\u00e4tzen. Diese kombinieren Sicherheit und Benutzerfreundlichkeit f\u00fcr eine optimale Lenkung der Ein- und Ausfahrten zu und von Ihren Einrichtungen.<\/p>\n<ul>\n<li>Verst\u00e4rkte Sicherheit und vollst\u00e4ndige Automatisierung<\/li>\n<li>Intelligente Zugangsverwaltung (Ausweise, Kennzeichenerkennung&#8230;)<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.portalp.com\/solutions\/acces-parking\/\">Mehr erfahren<\/a><\/p>\n<p>[\/dica_divi_carouselitem][dica_divi_carouselitem admin_label=&#8220;S\u00e9curit\u00e9 des b\u00e2timents&#8220; button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/iso-3.jpg&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; background_enable_color=&#8220;on&#8220; border_radii_item=&#8220;on|15px|15px|15px|15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Geb\u00e4udesicherheit<\/h3>\n<hr \/>\n<p>Sch\u00fctzen Sie Ihre Einrichtungen mit ma\u00dfgeschneiderten L\u00f6sungen. Mit unseren Zugangskontrollsystemen gew\u00e4hrleisten Sie dank modernster Identifikations- und \u00dcberwachungstechnologien eine erh\u00f6hte Sicherheit f\u00fcr Ihre Mitarbeiter und Ihre vertraulichen Daten.<\/p>\n<ul>\n<li>Sichere und individuell anpassbare Zugangskontrolle<\/li>\n<li>Integrierte Video\u00fcberwachung<\/li>\n<li>Kompatibilit\u00e4t mit bestehenden Sicherheitssystemen<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.portalp.com\/solutions\/securite-des-batiments\/\">Mehr erfahren<\/a><\/p>\n<p>[\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code disabled_on=&#8220;on|on|on&#8220; _builder_version=&#8220;4.27.2&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; height=&#8220;100%&#8220; custom_padding=&#8220;10px|10px|10px|10px|true|true&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI2NjgifX0=@&#8220; custom_css_main_element=&#8220;display: flex;||align-items: center;||justify-content: center&#8220; custom_css_free_form=&#8220;selector {||  text-align:center;||}||selector a {||  color: #b49988;||}&#8220; border_radii=&#8220;on|50px|50px|50px|50px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#B49988&#8243; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;]<a href=\"https:\/\/www.portalp.com\/outils-et-supports\/guide-de-choix\/\">Ber\u00fchrungslose<!\u2013- [et_pb_br_holder] -\u2013>Steuerung und Erkennung<\/a>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; custom_css_free_form=&#8220;selector .et_pb_button_module_wrapper {||  height:100%;||}&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.27.2&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_direction=&#8220;90deg&#8220; background_color_gradient_stops=&#8220;#0075bf 1%|#004876 100%&#8220; height=&#8220;100%&#8220; custom_padding=&#8220;10px|10px|10px|10px|true|true&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQxNDMifX0=@&#8220; custom_css_main_element=&#8220;display: flex;||align-items: center;||justify-content: center;&#8220; custom_css_free_form=&#8220;selector {||  text-align:center;||}||||selector a {||  color: #fff;||}&#8220; border_radii=&#8220;on|50px|50px|50px|50px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#E4DAD3&#8243; global_colors_info=&#8220;{}&#8220;]<a href=\"https:\/\/www.portalp.com\/de\/kontakte\/angebot-anfordern\/\">Angebot anfordern<\/a>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.27.2&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; height=&#8220;100%&#8220; custom_padding=&#8220;10px|10px|10px|10px|true|true&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEyNTc1In19@&#8220; custom_css_main_element=&#8220;display: flex;||align-items: center;||justify-content: center;&#8220; custom_css_free_form=&#8220;selector a {||  color: #b49988;||}&#8220; border_radii=&#8220;on|50px|50px|50px|50px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#B49988&#8243; global_colors_info=&#8220;{}&#8220;]<a href=\"https:\/\/www.portalp.com\/de\/services\/bauwerksdatenmodellierung\/\"><img decoding=\"async\" src=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/bim.png\" style=\"vertical-align:middle;margin-right:10px\">BIM \u2013 3D-Modellierung<\/a>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Zertifizierte Produkte mit dem Siegel \u201eOrigine France Garantie\u201c<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Unser gesamtes Sortiment an zusammengebauten automatischen Fu\u00dfg\u00e4ngert\u00fcren ist mit dem Zertifikat \u201eOrigine France Garantie\u201c ausgezeichnet.<\/p>\n<p>Diese Zertifizierung zeugt von unserem unersch\u00fctterlichen Willen, unseren Kunden stets Produkte anzubieten, deren franz\u00f6sische Herkunft klar und unbestreitbar ist.<\/p>\n<p>Das Siegel belegt unser Engagement f\u00fcr eine lokale und qualitativ hochwertige Produktion und tr\u00e4gt so zur Dynamisierung der franz\u00f6sischen Wirtschaft bei.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/07\/ofg-logo-1.png&#8220; alt=&#8220;Origine France Garantie&#8220; title_text=&#8220;ofg-logo&#8220; align=&#8220;center&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; max_width_tablet=&#8220;&#8220; max_width_phone=&#8220;50%&#8220; max_width_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;|||0px||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#E4DAD3&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; global_module=&#8220;50359&#8243; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h2>Die Zertifizierungen von Portalp<\/h2>\n<p>[\/et_pb_text][dica_divi_carousel show_items_desktop=&#8220;5&#8243; show_items_mobile=&#8220;3&#8243; loop=&#8220;on&#8220; autoplay=&#8220;on&#8220; scroller_effect=&#8220;on&#8220; item_vertical_align=&#8220;center&#8220; advanced_effect=&#8220;1&#8243; overlay_color_field_bgcolor=&#8220;rgba(255,255,255,0.85)&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][dica_divi_carouselitem button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/ecovadis-silver-2023.png&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/origine-france-garantie.png&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/qualibat.png&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2025\/10\/socotec-iso-9001-45001.jpg&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=&#8220;1&#8243; image=&#8220;https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/04\/afaq-iso9001-iso45001.png&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1ODU0In19@&#8220; button_text=&#8220;Hier finden Sie unsere Zertifizierungen&#8220; _builder_version=&#8220;4.27.2&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gastgewerbe &amp; RestaurantsVerbesserte Kundenerfahrung und optimierte betriebliche EffizienzVon der Installation automatischer T\u00fcren am Empfang und in der K\u00fcche \u00fcber die Verwaltung der Parkplatzzufahrten bis hin zur Sicherung Ihrer Geb\u00e4ude &#8211; mit unseren Produktl\u00f6sungen richten wir uns nach Ihren Bed\u00fcrfnissen. Damit k\u00f6nnen Sie sich auf das Wesentliche konzentrieren: die Bewirtung Ihrer G\u00e4ste.<span><span><a href=\"https:\/\/www.portalp.com\/de\/\">Startseite<\/a><\/span><\/span>Bei Portalp begleiten wir Fachleute [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18993,"parent":17335,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-18637","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gastgewerbe &amp; Restaurants | Portalp<\/title>\n<meta name=\"description\" content=\"Wir unterst\u00fctzen die Hotellerie- und Gastronomiebranche bei der Optimierung des Kundenerlebnisses: Empfang, Zugangserleichterung und Sicherheit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastgewerbe &amp; Restaurants | Portalp\" \/>\n<meta property=\"og:description\" content=\"Wir unterst\u00fctzen die Hotellerie- und Gastronomiebranche bei der Optimierung des Kundenerlebnisses: Empfang, Zugangserleichterung und Sicherheit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/\" \/>\n<meta property=\"og:site_name\" content=\"Portalp\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T14:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/10\/lumina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"961\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/\",\"name\":\"Gastgewerbe & Restaurants | Portalp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/lumina.jpg\",\"datePublished\":\"2024-04-12T12:18:42+00:00\",\"dateModified\":\"2025-10-17T14:59:51+00:00\",\"description\":\"Wir unterst\u00fctzen die Hotellerie- und Gastronomiebranche bei der Optimierung des Kundenerlebnisses: Empfang, Zugangserleichterung und Sicherheit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/lumina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/lumina.jpg\",\"width\":961,\"height\":641,\"caption\":\"Porte automatique Portalp dans un h\u00f4tel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/gastgewerbe-restaurants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Branchen\",\"item\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/branchen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gastgewerbe &#038; Restaurants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/\",\"name\":\"Portalp\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#organization\",\"name\":\"Portalp\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"contentUrl\":\"https:\\\/\\\/www.portalp.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-PORTALP_coul-72.png\",\"width\":375,\"height\":142,\"caption\":\"Portalp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portalp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/portalp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastgewerbe & Restaurants | Portalp","description":"Wir unterst\u00fctzen die Hotellerie- und Gastronomiebranche bei der Optimierung des Kundenerlebnisses: Empfang, Zugangserleichterung und Sicherheit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/","og_locale":"de_DE","og_type":"article","og_title":"Gastgewerbe & Restaurants | Portalp","og_description":"Wir unterst\u00fctzen die Hotellerie- und Gastronomiebranche bei der Optimierung des Kundenerlebnisses: Empfang, Zugangserleichterung und Sicherheit.","og_url":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/","og_site_name":"Portalp","article_modified_time":"2025-10-17T14:59:51+00:00","og_image":[{"width":961,"height":641,"url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/10\/lumina.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/","url":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/","name":"Gastgewerbe & Restaurants | Portalp","isPartOf":{"@id":"https:\/\/www.portalp.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/#primaryimage"},"image":{"@id":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/10\/lumina.jpg","datePublished":"2024-04-12T12:18:42+00:00","dateModified":"2025-10-17T14:59:51+00:00","description":"Wir unterst\u00fctzen die Hotellerie- und Gastronomiebranche bei der Optimierung des Kundenerlebnisses: Empfang, Zugangserleichterung und Sicherheit.","breadcrumb":{"@id":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/#primaryimage","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/10\/lumina.jpg","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/10\/lumina.jpg","width":961,"height":641,"caption":"Porte automatique Portalp dans un h\u00f4tel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalp.com\/de\/branchen\/gastgewerbe-restaurants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.portalp.com\/de\/"},{"@type":"ListItem","position":2,"name":"Branchen","item":"https:\/\/www.portalp.com\/de\/branchen\/"},{"@type":"ListItem","position":3,"name":"Gastgewerbe &#038; Restaurants"}]},{"@type":"WebSite","@id":"https:\/\/www.portalp.com\/de\/#website","url":"https:\/\/www.portalp.com\/de\/","name":"Portalp","description":"","publisher":{"@id":"https:\/\/www.portalp.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalp.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.portalp.com\/de\/#organization","name":"Portalp","url":"https:\/\/www.portalp.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.portalp.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","contentUrl":"https:\/\/www.portalp.com\/wp-content\/uploads\/2024\/05\/Logo-PORTALP_coul-72.png","width":375,"height":142,"caption":"Portalp"},"image":{"@id":"https:\/\/www.portalp.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/portalp"]}]}},"_links":{"self":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/pages\/18637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/comments?post=18637"}],"version-history":[{"count":0,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/pages\/18637\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/pages\/17335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/media\/18993"}],"wp:attachment":[{"href":"https:\/\/www.portalp.com\/de\/wp-json\/wp\/v2\/media?parent=18637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}